{"id":7331,"date":"2024-01-31T00:06:26","date_gmt":"2024-01-30T23:06:26","guid":{"rendered":"https:\/\/www.playabara.es\/hebergement\/villas\/"},"modified":"2024-05-15T13:01:07","modified_gmt":"2024-05-15T11:01:07","slug":"villas","status":"publish","type":"page","link":"https:\/\/www.playabara.es\/fr\/hebergement\/villas\/","title":{"rendered":"Villas"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"7331\" class=\"elementor elementor-7331 elementor-2715\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9dbf8e9 elementor-section-height-min-height cs-section-content-fullwidth cs-parallax-on-scroll cs_scroll_y_80 elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"9dbf8e9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" data-cs-parallax-y=\"80\" style=\"background-image: none;\" data-cs-background-image=\"https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/FOTO-PORTADA-NUESTROS-ALOJAMIENTOS.jpg\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-105b500 dark-color\" data-id=\"105b500\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f599258 elementor-widget elementor-widget-cs_title\" data-id=\"f599258\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"cs_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"cs-title-wrap text-center\">\t            <div class=\"cs-subtitle-wrap\"><span class=\"cs-subtitle color-white\">h\u00e9bergements<\/span><\/div>\t            <h1 class=\"cs-title\">\n\t                VILLAS\t            <\/h1>        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-b7ff887 custom-tabs-menu e-flex e-con-boxed e-con e-parent\" data-id=\"b7ff887\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dc6ff14 elementor-widget elementor-widget-cs_menu\" data-id=\"dc6ff14\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"cs_menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<nav class=\"cs-menu main-navigation not-mobile-menu dropdown-dark text-center\"><ul id=\"menu-dc6ff14\" class=\"menu primary-menu\"><li id=\"menu-item-7493\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7493\"><a href=\"https:\/\/www.playabara.es\/fr\/hebergement\/bungalows\/\"><span>Bungalows<\/span><\/a><\/li>\n<li id=\"menu-item-7494\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7494\"><a href=\"https:\/\/www.playabara.es\/fr\/hebergement\/villas\/\"><span>Villas<\/span><\/a><\/li>\n<li id=\"menu-item-7495\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7495\"><a href=\"https:\/\/www.playabara.es\/fr\/hebergement\/emplacement\/\"><span>Emplacement<\/span><\/a><\/li>\n<\/ul><\/nav>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-10e74de elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"10e74de\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bf172eb\" data-id=\"bf172eb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fb2fa9b elementor-widget elementor-widget-cs_title\" data-id=\"fb2fa9b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"cs_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"cs-title-wrap text-center\">\t            <div class=\"cs-subtitle-wrap\"><span class=\"cs-subtitle\">ENTI\u00c8REMENT \u00c9QUIP\u00c9<\/span><\/div>\t            <h5 class=\"cs-title\">\n\t                Villas\t            <\/h5>\t            <div class=\"cs-title-text\">\n\t                <p>Dans nos villas, vous trouverez le confort dont vous avez besoin pour vos vacances en famille, enti\u00e8rement \u00e9quip\u00e9es pour devenir votre s\u00e9jour id\u00e9al afin que vous puissiez profiter de l&rsquo;exp\u00e9rience.<\/p>\n\t            <\/div>        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-63ed144 elementor-widget elementor-widget-cs_blog\" data-id=\"63ed144\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"cs_blog.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"posts text-center layout-zigzag layout-list img-ratio-3-2\">\n\t\t\t\t\t\t\t\t\t<div class=\"posts-wrapper\">\n<article class=\"post-7172 post type-post status-publish format-standard has-post-thumbnail hentry category-chambres category-villas-fr\">\n            <div class=\"featured-img\">\n        \t<a href=\"https:\/\/www.playabara.es\/fr\/villa-romulus\/\"><img fetchpriority=\"high\" decoding=\"async\" width=\"780\" height=\"585\" src=\"https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-ROMULUS-1-scaled-1-780x585.jpg\" class=\"attachment-cozystay_780x9999 size-cozystay_780x9999 wp-post-image\" alt=\"\" srcset=\"https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-ROMULUS-1-scaled-1-780x585.jpg 780w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-ROMULUS-1-scaled-1-300x225.jpg 300w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-ROMULUS-1-scaled-1-1024x768.jpg 1024w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-ROMULUS-1-scaled-1-768x576.jpg 768w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-ROMULUS-1-scaled-1-1536x1152.jpg 1536w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-ROMULUS-1-scaled-1-2048x1536.jpg 2048w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-ROMULUS-1-scaled-1-1920x1440.jpg 1920w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-ROMULUS-1-scaled-1-1440x1080.jpg 1440w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-ROMULUS-1-scaled-1-1200x900.jpg 1200w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-ROMULUS-1-scaled-1-600x450.jpg 600w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-ROMULUS-1-scaled-1-550x413.jpg 550w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-ROMULUS-1-scaled-1-370x278.jpg 370w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-ROMULUS-1-scaled-1-255x191.jpg 255w\" sizes=\"(max-width: 780px) 100vw, 780px\" \/><\/a>        <\/div>\n\t<div class=\"post-content\">\n\t\t<header class=\"post-header\">            <div class=\"meta-wrap\">\t\t\t<div class=\"cat-links\"><a href=\"https:\/\/www.playabara.es\/fr\/category\/chambres\/\" rel=\"tag\">Chambres<\/a> <a href=\"https:\/\/www.playabara.es\/fr\/category\/chambres\/villas-fr\/\" rel=\"tag\">Villas<\/a><\/div>            <\/div>    <h2 class=\"post-title\">\n        <a href=\"https:\/\/www.playabara.es\/fr\/villa-romulus\/\">VILLA ROMULUS<\/a>\n    <\/h2>\t\t\t\t\t\t\t\t\t\t\t<ul class=\"habitabilidad-list center\">\n\t\t\t\t\t<li><img decoding=\"async\" src=\"https:\/\/barapark.es\/wp-content\/uploads\/2024\/03\/icon-metros.png\">3<\/li>\n\t\t\t\t\t<li><img decoding=\"async\" src=\"https:\/\/barapark.es\/wp-content\/uploads\/2024\/03\/icon-user.png\">6<\/li>\n\t\t\t\t\t<li><img decoding=\"async\" src=\"https:\/\/barapark.es\/wp-content\/uploads\/2024\/03\/icon-bed.png\">5<\/li>\n\t\t\t\t\t<li><img decoding=\"async\" src=\"https:\/\/barapark.es\/wp-content\/uploads\/2024\/03\/icon-water.png\">1 salle de bain<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t\t\t<\/header>\t\t<div class=\"post-excerpt\"><p>Villa catalane situ\u00e9e au centre du camping, pouvant accueillir jusqu&rsquo;\u00e0 6 personnes. Distribu\u00e9 avec 3 chambres (1 double, une avec un lit superpos\u00e9 et un &#8230;<\/p>\n<\/div>             <footer class=\"post-footer\">\n\t\t\t\t<a class='read-more-btn button cs-btn-underline' href='https:\/\/www.playabara.es\/fr\/villa-romulus\/'><span>Plus d'informations<\/span><\/a>\n\t\t\t\t\t\t\t\t\n\t\t\t<a href=\"https:\/\/booking.playabara.es\/search?lang=fr\" class=\"read-more-btn button cs-btn-underline\">\n\t\t\t\t<span>R\u00e9servation<\/span>\n\t\t\t<\/a>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n            <\/footer>\t<\/div>\n<\/article>\n\n<article class=\"post-7176 post type-post status-publish format-standard has-post-thumbnail hentry category-chambres category-villas-fr\">\n            <div class=\"featured-img\">\n        \t<a href=\"https:\/\/www.playabara.es\/fr\/villa-remus\/\"><img decoding=\"async\" width=\"780\" height=\"517\" src=\"https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-78-8-780x517.jpg\" class=\"attachment-cozystay_780x9999 size-cozystay_780x9999 wp-post-image\" alt=\"\" srcset=\"https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-78-8-780x517.jpg 780w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-78-8-300x199.jpg 300w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-78-8-1024x678.jpg 1024w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-78-8-768x509.jpg 768w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-78-8-1536x1017.jpg 1536w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-78-8-2048x1356.jpg 2048w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-78-8-1920x1272.jpg 1920w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-78-8-1440x954.jpg 1440w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-78-8-1200x795.jpg 1200w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-78-8-600x397.jpg 600w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-78-8-550x364.jpg 550w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-78-8-370x245.jpg 370w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-78-8-255x169.jpg 255w\" sizes=\"(max-width: 780px) 100vw, 780px\" \/><\/a>        <\/div>\n\t<div class=\"post-content\">\n\t\t<header class=\"post-header\">            <div class=\"meta-wrap\">\t\t\t<div class=\"cat-links\"><a href=\"https:\/\/www.playabara.es\/fr\/category\/chambres\/\" rel=\"tag\">Chambres<\/a> <a href=\"https:\/\/www.playabara.es\/fr\/category\/chambres\/villas-fr\/\" rel=\"tag\">Villas<\/a><\/div>            <\/div>    <h2 class=\"post-title\">\n        <a href=\"https:\/\/www.playabara.es\/fr\/villa-remus\/\">VILLA REMUS<\/a>\n    <\/h2>\t\t\t\t\t\t\t\t\t\t\t<ul class=\"habitabilidad-list center\">\n\t\t\t\t\t<li><img decoding=\"async\" src=\"https:\/\/barapark.es\/wp-content\/uploads\/2024\/03\/icon-metros.png\">3<\/li>\n\t\t\t\t\t<li><img decoding=\"async\" src=\"https:\/\/barapark.es\/wp-content\/uploads\/2024\/03\/icon-user.png\">6<\/li>\n\t\t\t\t\t<li><img decoding=\"async\" src=\"https:\/\/barapark.es\/wp-content\/uploads\/2024\/03\/icon-bed.png\">5<\/li>\n\t\t\t\t\t<li><img decoding=\"async\" src=\"https:\/\/barapark.es\/wp-content\/uploads\/2024\/03\/icon-water.png\">1 salle de bain<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t\t\t<\/header>\t\t<div class=\"post-excerpt\"><p>Villa catalane situ\u00e9e au centre du camping, pouvant accueillir jusqu&rsquo;\u00e0 6 personnes. Distribu\u00e9 avec 3 chambres (1 double, une avec un lit superpos\u00e9 et un &#8230;<\/p>\n<\/div>             <footer class=\"post-footer\">\n\t\t\t\t<a class='read-more-btn button cs-btn-underline' href='https:\/\/www.playabara.es\/fr\/villa-remus\/'><span>Plus d'informations<\/span><\/a>\n\t\t\t\t\t\t\t\t\n\t\t\t<a href=\"https:\/\/booking.playabara.es\/search?lang=fr\" class=\"read-more-btn button cs-btn-underline\">\n\t\t\t\t<span>R\u00e9servation<\/span>\n\t\t\t<\/a>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n            <\/footer>\t<\/div>\n<\/article>\n\n<article class=\"post-7179 post type-post status-publish format-standard has-post-thumbnail hentry category-chambres category-villas-fr\">\n            <div class=\"featured-img\">\n        \t<a href=\"https:\/\/www.playabara.es\/fr\/villa-octavia\/\"><img decoding=\"async\" width=\"780\" height=\"517\" src=\"https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-OCTAVIA-1-780x517.jpg\" class=\"attachment-cozystay_780x9999 size-cozystay_780x9999 wp-post-image\" alt=\"\" srcset=\"https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-OCTAVIA-1-780x517.jpg 780w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-OCTAVIA-1-300x199.jpg 300w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-OCTAVIA-1-1024x678.jpg 1024w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-OCTAVIA-1-768x509.jpg 768w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-OCTAVIA-1-1536x1017.jpg 1536w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-OCTAVIA-1-1920x1272.jpg 1920w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-OCTAVIA-1-1440x954.jpg 1440w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-OCTAVIA-1-1200x795.jpg 1200w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-OCTAVIA-1-600x397.jpg 600w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-OCTAVIA-1-550x364.jpg 550w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-OCTAVIA-1-370x245.jpg 370w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-OCTAVIA-1-255x169.jpg 255w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-OCTAVIA-1.jpg 1928w\" sizes=\"(max-width: 780px) 100vw, 780px\" \/><\/a>        <\/div>\n\t<div class=\"post-content\">\n\t\t<header class=\"post-header\">            <div class=\"meta-wrap\">\t\t\t<div class=\"cat-links\"><a href=\"https:\/\/www.playabara.es\/fr\/category\/chambres\/\" rel=\"tag\">Chambres<\/a> <a href=\"https:\/\/www.playabara.es\/fr\/category\/chambres\/villas-fr\/\" rel=\"tag\">Villas<\/a><\/div>            <\/div>    <h2 class=\"post-title\">\n        <a href=\"https:\/\/www.playabara.es\/fr\/villa-octavia\/\">VILLA OCTAVIA<\/a>\n    <\/h2>\t\t\t\t\t\t\t\t\t\t\t<ul class=\"habitabilidad-list center\">\n\t\t\t\t\t<li><img decoding=\"async\" src=\"https:\/\/barapark.es\/wp-content\/uploads\/2024\/03\/icon-metros.png\">2<\/li>\n\t\t\t\t\t<li><img decoding=\"async\" src=\"https:\/\/barapark.es\/wp-content\/uploads\/2024\/03\/icon-user.png\">5<\/li>\n\t\t\t\t\t<li><img decoding=\"async\" src=\"https:\/\/barapark.es\/wp-content\/uploads\/2024\/03\/icon-bed.png\">3<\/li>\n\t\t\t\t\t<li><img decoding=\"async\" src=\"https:\/\/barapark.es\/wp-content\/uploads\/2024\/03\/icon-water.png\">1 salle de bain<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t\t\t<\/header>\t\t<div class=\"post-excerpt\"><p>Villa catalane situ\u00e9e au premier \u00e9tage pouvant accueillir jusqu&rsquo;\u00e0 5 personnes. Distribu\u00e9e avec 2 chambres (1 double et 1 avec lit superpos\u00e9 et un lit &#8230;<\/p>\n<\/div>             <footer class=\"post-footer\">\n\t\t\t\t<a class='read-more-btn button cs-btn-underline' href='https:\/\/www.playabara.es\/fr\/villa-octavia\/'><span>Plus d'informations<\/span><\/a>\n\t\t\t\t\t\t\t\t\n\t\t\t<a href=\"https:\/\/booking.playabara.es\/search?lang=fr\" class=\"read-more-btn button cs-btn-underline\">\n\t\t\t\t<span>R\u00e9servation<\/span>\n\t\t\t<\/a>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n            <\/footer>\t<\/div>\n<\/article>\n\n<article class=\"post-7184 post type-post status-publish format-standard has-post-thumbnail hentry category-chambres category-villas-fr\">\n            <div class=\"featured-img\">\n        \t<a href=\"https:\/\/www.playabara.es\/fr\/villa-livia\/\"><img loading=\"lazy\" decoding=\"async\" width=\"780\" height=\"522\" src=\"https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-LIVIA-1-scaled-1-780x522.jpg\" class=\"attachment-cozystay_780x9999 size-cozystay_780x9999 wp-post-image\" alt=\"\" srcset=\"https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-LIVIA-1-scaled-1-780x522.jpg 780w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-LIVIA-1-scaled-1-300x201.jpg 300w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-LIVIA-1-scaled-1-1024x686.jpg 1024w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-LIVIA-1-scaled-1-768x514.jpg 768w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-LIVIA-1-scaled-1-1536x1028.jpg 1536w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-LIVIA-1-scaled-1-2048x1371.jpg 2048w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-LIVIA-1-scaled-1-1920x1286.jpg 1920w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-LIVIA-1-scaled-1-1440x964.jpg 1440w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-LIVIA-1-scaled-1-1200x803.jpg 1200w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-LIVIA-1-scaled-1-600x402.jpg 600w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-LIVIA-1-scaled-1-550x368.jpg 550w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-LIVIA-1-scaled-1-370x248.jpg 370w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-LIVIA-1-scaled-1-255x171.jpg 255w\" sizes=\"(max-width: 780px) 100vw, 780px\" \/><\/a>        <\/div>\n\t<div class=\"post-content\">\n\t\t<header class=\"post-header\">            <div class=\"meta-wrap\">\t\t\t<div class=\"cat-links\"><a href=\"https:\/\/www.playabara.es\/fr\/category\/chambres\/\" rel=\"tag\">Chambres<\/a> <a href=\"https:\/\/www.playabara.es\/fr\/category\/chambres\/villas-fr\/\" rel=\"tag\">Villas<\/a><\/div>            <\/div>    <h2 class=\"post-title\">\n        <a href=\"https:\/\/www.playabara.es\/fr\/villa-livia\/\">VILLA LIVIA<\/a>\n    <\/h2>\t\t\t\t\t\t\t\t\t\t\t<ul class=\"habitabilidad-list center\">\n\t\t\t\t\t<li><img decoding=\"async\" src=\"https:\/\/barapark.es\/wp-content\/uploads\/2024\/03\/icon-metros.png\">2<\/li>\n\t\t\t\t\t<li><img decoding=\"async\" src=\"https:\/\/barapark.es\/wp-content\/uploads\/2024\/03\/icon-user.png\">6<\/li>\n\t\t\t\t\t<li><img decoding=\"async\" src=\"https:\/\/barapark.es\/wp-content\/uploads\/2024\/03\/icon-bed.png\">5<\/li>\n\t\t\t\t\t<li><img decoding=\"async\" src=\"https:\/\/barapark.es\/wp-content\/uploads\/2024\/03\/icon-water.png\">2 salles de bains<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t\t\t<\/header>\t\t<div class=\"post-excerpt\"><p>Villa catalane de deux \u00e9tages situ\u00e9e \u00e0 c\u00f4t\u00e9 d&rsquo;une piscine de deux \u00e9tages, pouvant accueillir jusqu&rsquo;\u00e0 6 personnes. Distribu\u00e9e au premier \u00e9tage avec acc\u00e8s par &#8230;<\/p>\n<\/div>             <footer class=\"post-footer\">\n\t\t\t\t<a class='read-more-btn button cs-btn-underline' href='https:\/\/www.playabara.es\/fr\/villa-livia\/'><span>Plus d'informations<\/span><\/a>\n\t\t\t\t\t\t\t\t\n\t\t\t<a href=\"https:\/\/booking.playabara.es\/search?lang=fr\" class=\"read-more-btn button cs-btn-underline\">\n\t\t\t\t<span>R\u00e9servation<\/span>\n\t\t\t<\/a>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n            <\/footer>\t<\/div>\n<\/article>\n\n<article class=\"post-7188 post type-post status-publish format-standard has-post-thumbnail hentry category-chambres category-villas-fr\">\n            <div class=\"featured-img\">\n        \t<a href=\"https:\/\/www.playabara.es\/fr\/villa-julia\/\"><img loading=\"lazy\" decoding=\"async\" width=\"780\" height=\"522\" src=\"https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-JULIA-scaled-1-780x522.jpeg\" class=\"attachment-cozystay_780x9999 size-cozystay_780x9999 wp-post-image\" alt=\"\" srcset=\"https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-JULIA-scaled-1-780x522.jpeg 780w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-JULIA-scaled-1-300x201.jpeg 300w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-JULIA-scaled-1-1024x686.jpeg 1024w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-JULIA-scaled-1-768x514.jpeg 768w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-JULIA-scaled-1-1536x1028.jpeg 1536w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-JULIA-scaled-1-2048x1371.jpeg 2048w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-JULIA-scaled-1-1920x1286.jpeg 1920w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-JULIA-scaled-1-1440x964.jpeg 1440w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-JULIA-scaled-1-1200x803.jpeg 1200w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-JULIA-scaled-1-600x402.jpeg 600w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-JULIA-scaled-1-550x368.jpeg 550w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-JULIA-scaled-1-370x248.jpeg 370w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-JULIA-scaled-1-255x171.jpeg 255w\" sizes=\"(max-width: 780px) 100vw, 780px\" \/><\/a>        <\/div>\n\t<div class=\"post-content\">\n\t\t<header class=\"post-header\">            <div class=\"meta-wrap\">\t\t\t<div class=\"cat-links\"><a href=\"https:\/\/www.playabara.es\/fr\/category\/chambres\/\" rel=\"tag\">Chambres<\/a> <a href=\"https:\/\/www.playabara.es\/fr\/category\/chambres\/villas-fr\/\" rel=\"tag\">Villas<\/a><\/div>            <\/div>    <h2 class=\"post-title\">\n        <a href=\"https:\/\/www.playabara.es\/fr\/villa-julia\/\">VILLA JULIA<\/a>\n    <\/h2>\t\t\t\t\t\t\t\t\t\t\t<ul class=\"habitabilidad-list center\">\n\t\t\t\t\t<li><img decoding=\"async\" src=\"https:\/\/barapark.es\/wp-content\/uploads\/2024\/03\/icon-metros.png\">2<\/li>\n\t\t\t\t\t<li><img decoding=\"async\" src=\"https:\/\/barapark.es\/wp-content\/uploads\/2024\/03\/icon-user.png\">5<\/li>\n\t\t\t\t\t<li><img decoding=\"async\" src=\"https:\/\/barapark.es\/wp-content\/uploads\/2024\/03\/icon-bed.png\">4<\/li>\n\t\t\t\t\t<li><img decoding=\"async\" src=\"https:\/\/barapark.es\/wp-content\/uploads\/2024\/03\/icon-water.png\">1 salle de bain<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t\t\t<\/header>\t\t<div class=\"post-excerpt\"><p>Villa catalane situ\u00e9e au rez-de-chauss\u00e9e avec acc\u00e8s par 3 marches, pouvant accueillir jusqu&rsquo;\u00e0 5 personnes. Distribu\u00e9e avec 2 chambres (1 double et une autre avec &#8230;<\/p>\n<\/div>             <footer class=\"post-footer\">\n\t\t\t\t<a class='read-more-btn button cs-btn-underline' href='https:\/\/www.playabara.es\/fr\/villa-julia\/'><span>Plus d'informations<\/span><\/a>\n\t\t\t\t\t\t\t\t\n\t\t\t<a href=\"https:\/\/booking.playabara.es\/search?lang=fr\" class=\"read-more-btn button cs-btn-underline\">\n\t\t\t\t<span>R\u00e9servation<\/span>\n\t\t\t<\/a>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n            <\/footer>\t<\/div>\n<\/article>\n\n<article class=\"post-7192 post type-post status-publish format-standard has-post-thumbnail hentry category-chambres category-villas-fr\">\n            <div class=\"featured-img\">\n        \t<a href=\"https:\/\/www.playabara.es\/fr\/villa-flavia\/\"><img loading=\"lazy\" decoding=\"async\" width=\"780\" height=\"517\" src=\"https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-FLAVIA-scaled-2-780x517.jpg\" class=\"attachment-cozystay_780x9999 size-cozystay_780x9999 wp-post-image\" alt=\"\" srcset=\"https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-FLAVIA-scaled-2-780x517.jpg 780w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-FLAVIA-scaled-2-300x199.jpg 300w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-FLAVIA-scaled-2-1024x678.jpg 1024w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-FLAVIA-scaled-2-768x509.jpg 768w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-FLAVIA-scaled-2-1536x1018.jpg 1536w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-FLAVIA-scaled-2-2048x1357.jpg 2048w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-FLAVIA-scaled-2-1920x1272.jpg 1920w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-FLAVIA-scaled-2-1440x954.jpg 1440w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-FLAVIA-scaled-2-1200x795.jpg 1200w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-FLAVIA-scaled-2-600x398.jpg 600w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-FLAVIA-scaled-2-550x364.jpg 550w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-FLAVIA-scaled-2-370x245.jpg 370w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-FLAVIA-scaled-2-255x169.jpg 255w\" sizes=\"(max-width: 780px) 100vw, 780px\" \/><\/a>        <\/div>\n\t<div class=\"post-content\">\n\t\t<header class=\"post-header\">            <div class=\"meta-wrap\">\t\t\t<div class=\"cat-links\"><a href=\"https:\/\/www.playabara.es\/fr\/category\/chambres\/\" rel=\"tag\">Chambres<\/a> <a href=\"https:\/\/www.playabara.es\/fr\/category\/chambres\/villas-fr\/\" rel=\"tag\">Villas<\/a><\/div>            <\/div>    <h2 class=\"post-title\">\n        <a href=\"https:\/\/www.playabara.es\/fr\/villa-flavia\/\">VILLA FLAVIA<\/a>\n    <\/h2>\t\t\t\t\t\t\t\t\t\t\t<ul class=\"habitabilidad-list center\">\n\t\t\t\t\t<li><img decoding=\"async\" src=\"https:\/\/barapark.es\/wp-content\/uploads\/2024\/03\/icon-metros.png\">2<\/li>\n\t\t\t\t\t<li><img decoding=\"async\" src=\"https:\/\/barapark.es\/wp-content\/uploads\/2024\/03\/icon-user.png\">5<\/li>\n\t\t\t\t\t<li><img decoding=\"async\" src=\"https:\/\/barapark.es\/wp-content\/uploads\/2024\/03\/icon-bed.png\">4<\/li>\n\t\t\t\t\t<li><img decoding=\"async\" src=\"https:\/\/barapark.es\/wp-content\/uploads\/2024\/03\/icon-water.png\">1 salle de bain<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t\t\t<\/header>\t\t<div class=\"post-excerpt\"><p>Villa catalane situ\u00e9e au rez-de-chauss\u00e9e avec acc\u00e8s par 2 marches, avec possibilit\u00e9 d&rsquo;entr\u00e9e handicap\u00e9s, pouvant accueillir jusqu&rsquo;\u00e0 5 personnes. Distribu\u00e9e avec 2 chambres (1 double &#8230;<\/p>\n<\/div>             <footer class=\"post-footer\">\n\t\t\t\t<a class='read-more-btn button cs-btn-underline' href='https:\/\/www.playabara.es\/fr\/villa-flavia\/'><span>Plus d'informations<\/span><\/a>\n\t\t\t\t\t\t\t\t\n\t\t\t<a href=\"https:\/\/booking.playabara.es\/search?lang=fr\" class=\"read-more-btn button cs-btn-underline\">\n\t\t\t\t<span>R\u00e9servation<\/span>\n\t\t\t<\/a>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n            <\/footer>\t<\/div>\n<\/article>\n\n<article class=\"post-7196 post type-post status-publish format-standard has-post-thumbnail hentry category-chambres category-villas-fr\">\n            <div class=\"featured-img\">\n        \t<a href=\"https:\/\/www.playabara.es\/fr\/villa-cesar\/\"><img loading=\"lazy\" decoding=\"async\" width=\"780\" height=\"508\" src=\"https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-CESAR-780x508.jpg\" class=\"attachment-cozystay_780x9999 size-cozystay_780x9999 wp-post-image\" alt=\"\" srcset=\"https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-CESAR-780x508.jpg 780w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-CESAR-300x196.jpg 300w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-CESAR-1024x667.jpg 1024w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-CESAR-768x501.jpg 768w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-CESAR-600x391.jpg 600w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-CESAR-550x359.jpg 550w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-CESAR-370x241.jpg 370w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-CESAR-255x166.jpg 255w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-CESAR.jpg 1080w\" sizes=\"(max-width: 780px) 100vw, 780px\" \/><\/a>        <\/div>\n\t<div class=\"post-content\">\n\t\t<header class=\"post-header\">            <div class=\"meta-wrap\">\t\t\t<div class=\"cat-links\"><a href=\"https:\/\/www.playabara.es\/fr\/category\/chambres\/\" rel=\"tag\">Chambres<\/a> <a href=\"https:\/\/www.playabara.es\/fr\/category\/chambres\/villas-fr\/\" rel=\"tag\">Villas<\/a><\/div>            <\/div>    <h2 class=\"post-title\">\n        <a href=\"https:\/\/www.playabara.es\/fr\/villa-cesar\/\">VILLA CESAR<\/a>\n    <\/h2>\t\t\t\t\t\t\t\t\t\t\t<ul class=\"habitabilidad-list center\">\n\t\t\t\t\t<li><img decoding=\"async\" src=\"https:\/\/barapark.es\/wp-content\/uploads\/2024\/03\/icon-metros.png\">3<\/li>\n\t\t\t\t\t<li><img decoding=\"async\" src=\"https:\/\/barapark.es\/wp-content\/uploads\/2024\/03\/icon-user.png\">7<\/li>\n\t\t\t\t\t<li><img decoding=\"async\" src=\"https:\/\/barapark.es\/wp-content\/uploads\/2024\/03\/icon-bed.png\">6<\/li>\n\t\t\t\t\t<li><img decoding=\"async\" src=\"https:\/\/barapark.es\/wp-content\/uploads\/2024\/03\/icon-water.png\">2 salles de bains<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t\t\t<\/header>\t\t<div class=\"post-excerpt\"><p>Villa catalane sur 2 \u00e9tages, situ\u00e9e au rez-de-chauss\u00e9e avec acc\u00e8s par 3 marches et une rampe lat\u00e9rale, pouvant accueillir jusqu&rsquo;\u00e0 7 personnes. Distribu\u00e9 avec 3 &#8230;<\/p>\n<\/div>             <footer class=\"post-footer\">\n\t\t\t\t<a class='read-more-btn button cs-btn-underline' href='https:\/\/www.playabara.es\/fr\/villa-cesar\/'><span>Plus d'informations<\/span><\/a>\n\t\t\t\t\t\t\t\t\n\t\t\t<a href=\"https:\/\/booking.playabara.es\/search?lang=fr\" class=\"read-more-btn button cs-btn-underline\">\n\t\t\t\t<span>R\u00e9servation<\/span>\n\t\t\t<\/a>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n            <\/footer>\t<\/div>\n<\/article>\n\n<article class=\"post-7199 post type-post status-publish format-standard has-post-thumbnail hentry category-chambres category-villas-fr\">\n            <div class=\"featured-img\">\n        \t<a href=\"https:\/\/www.playabara.es\/fr\/villa-augusta\/\"><img loading=\"lazy\" decoding=\"async\" width=\"780\" height=\"520\" src=\"https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-AUGUSTA-scaled-1-780x520.jpg\" class=\"attachment-cozystay_780x9999 size-cozystay_780x9999 wp-post-image\" alt=\"\" srcset=\"https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-AUGUSTA-scaled-1-780x520.jpg 780w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-AUGUSTA-scaled-1-300x200.jpg 300w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-AUGUSTA-scaled-1-1024x683.jpg 1024w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-AUGUSTA-scaled-1-768x512.jpg 768w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-AUGUSTA-scaled-1-1536x1024.jpg 1536w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-AUGUSTA-scaled-1-2048x1366.jpg 2048w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-AUGUSTA-scaled-1-1920x1280.jpg 1920w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-AUGUSTA-scaled-1-1440x960.jpg 1440w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-AUGUSTA-scaled-1-1200x800.jpg 1200w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-AUGUSTA-scaled-1-600x400.jpg 600w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-AUGUSTA-scaled-1-550x367.jpg 550w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-AUGUSTA-scaled-1-370x247.jpg 370w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-AUGUSTA-scaled-1-255x170.jpg 255w\" sizes=\"(max-width: 780px) 100vw, 780px\" \/><\/a>        <\/div>\n\t<div class=\"post-content\">\n\t\t<header class=\"post-header\">            <div class=\"meta-wrap\">\t\t\t<div class=\"cat-links\"><a href=\"https:\/\/www.playabara.es\/fr\/category\/chambres\/\" rel=\"tag\">Chambres<\/a> <a href=\"https:\/\/www.playabara.es\/fr\/category\/chambres\/villas-fr\/\" rel=\"tag\">Villas<\/a><\/div>            <\/div>    <h2 class=\"post-title\">\n        <a href=\"https:\/\/www.playabara.es\/fr\/villa-augusta\/\">VILLA AUGUSTA<\/a>\n    <\/h2>\t\t\t\t\t\t\t\t\t\t\t<ul class=\"habitabilidad-list center\">\n\t\t\t\t\t<li><img decoding=\"async\" src=\"https:\/\/barapark.es\/wp-content\/uploads\/2024\/03\/icon-metros.png\">30<\/li>\n\t\t\t\t\t<li><img decoding=\"async\" src=\"https:\/\/barapark.es\/wp-content\/uploads\/2024\/03\/icon-user.png\">5<\/li>\n\t\t\t\t\t<li><img decoding=\"async\" src=\"https:\/\/barapark.es\/wp-content\/uploads\/2024\/03\/icon-bed.png\">3<\/li>\n\t\t\t\t\t<li><img decoding=\"async\" src=\"https:\/\/barapark.es\/wp-content\/uploads\/2024\/03\/icon-water.png\">1 salle de bain<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t\t\t<\/header>\t\t<div class=\"post-excerpt\"><p>Villa catalane situ\u00e9e au centre du camping, pouvant accueillir jusqu&rsquo;\u00e0 5 personnes. Distribu\u00e9e avec 3 chambres (1 suite double avec salle de bain, une avec &#8230;<\/p>\n<\/div>             <footer class=\"post-footer\">\n\t\t\t\t<a class='read-more-btn button cs-btn-underline' href='https:\/\/www.playabara.es\/fr\/villa-augusta\/'><span>Plus d'informations<\/span><\/a>\n\t\t\t\t\t\t\t\t\n\t\t\t<a href=\"https:\/\/booking.playabara.es\/search?lang=fr\" class=\"read-more-btn button cs-btn-underline\">\n\t\t\t\t<span>R\u00e9servation<\/span>\n\t\t\t<\/a>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n            <\/footer>\t<\/div>\n<\/article>\n\n<article class=\"post-7205 post type-post status-publish format-standard has-post-thumbnail hentry category-chambres category-villas-fr\">\n            <div class=\"featured-img\">\n        \t<a href=\"https:\/\/www.playabara.es\/fr\/villa-apia\/\"><img loading=\"lazy\" decoding=\"async\" width=\"780\" height=\"522\" src=\"https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-APIA-1-scaled-1-780x522.jpeg\" class=\"attachment-cozystay_780x9999 size-cozystay_780x9999 wp-post-image\" alt=\"\" srcset=\"https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-APIA-1-scaled-1-780x522.jpeg 780w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-APIA-1-scaled-1-300x201.jpeg 300w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-APIA-1-scaled-1-1024x686.jpeg 1024w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-APIA-1-scaled-1-768x514.jpeg 768w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-APIA-1-scaled-1-1536x1028.jpeg 1536w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-APIA-1-scaled-1-2048x1371.jpeg 2048w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-APIA-1-scaled-1-1920x1286.jpeg 1920w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-APIA-1-scaled-1-1440x964.jpeg 1440w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-APIA-1-scaled-1-1200x803.jpeg 1200w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-APIA-1-scaled-1-600x402.jpeg 600w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-APIA-1-scaled-1-550x368.jpeg 550w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-APIA-1-scaled-1-370x248.jpeg 370w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-APIA-1-scaled-1-255x171.jpeg 255w\" sizes=\"(max-width: 780px) 100vw, 780px\" \/><\/a>        <\/div>\n\t<div class=\"post-content\">\n\t\t<header class=\"post-header\">            <div class=\"meta-wrap\">\t\t\t<div class=\"cat-links\"><a href=\"https:\/\/www.playabara.es\/fr\/category\/chambres\/\" rel=\"tag\">Chambres<\/a> <a href=\"https:\/\/www.playabara.es\/fr\/category\/chambres\/villas-fr\/\" rel=\"tag\">Villas<\/a><\/div>            <\/div>    <h2 class=\"post-title\">\n        <a href=\"https:\/\/www.playabara.es\/fr\/villa-apia\/\">VILLA APIA<\/a>\n    <\/h2>\t\t\t\t\t\t\t\t\t\t\t<ul class=\"habitabilidad-list center\">\n\t\t\t\t\t<li><img decoding=\"async\" src=\"https:\/\/barapark.es\/wp-content\/uploads\/2024\/03\/icon-metros.png\">2<\/li>\n\t\t\t\t\t<li><img decoding=\"async\" src=\"https:\/\/barapark.es\/wp-content\/uploads\/2024\/03\/icon-user.png\">4<\/li>\n\t\t\t\t\t<li><img decoding=\"async\" src=\"https:\/\/barapark.es\/wp-content\/uploads\/2024\/03\/icon-bed.png\">3<\/li>\n\t\t\t\t\t<li><img decoding=\"async\" src=\"https:\/\/barapark.es\/wp-content\/uploads\/2024\/03\/icon-water.png\">1 salle de bain<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t\t\t<\/header>\t\t<div class=\"post-excerpt\"><p>Villa catalane situ\u00e9e au premier \u00e9tage, pouvant accueillir jusqu&rsquo;\u00e0 4 personnes. Elle dispose de 2 chambres (1 double et 1 twin), d&rsquo;une salle de bain &#8230;<\/p>\n<\/div>             <footer class=\"post-footer\">\n\t\t\t\t<a class='read-more-btn button cs-btn-underline' href='https:\/\/www.playabara.es\/fr\/villa-apia\/'><span>Plus d'informations<\/span><\/a>\n\t\t\t\t\t\t\t\t\n\t\t\t<a href=\"https:\/\/booking.playabara.es\/search?lang=fr\" class=\"read-more-btn button cs-btn-underline\">\n\t\t\t\t<span>R\u00e9servation<\/span>\n\t\t\t<\/a>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n            <\/footer>\t<\/div>\n<\/article>\n\t\t\t\t<\/div>\t\t\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2b558cc cs-section-content-fullwidth elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2b558cc\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a7e1fa0\" data-id=\"a7e1fa0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-14cc592 elementor-invisible elementor-widget elementor-widget-cs_info_box\" data-id=\"14cc592\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"cs_info_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t\t<div class=\"cs-info-box column-3 valign-middle img-left\">\n                <div class=\"cs-info-box-wrap\">                    <div class=\"cs-info-box-item elementor-repeater-item-6460937\">\n                    \t<div class=\"cs-item-container\">\t                        <div class=\"cs-info-box-img\"><i aria-hidden=\"true\" class=\"flaticon flaticon-review\"><\/i>\t                        <\/div>\t                        <div class=\"cs-info-box-content\">\n\t                            <h5 class=\"cs-title cs-info-box-title\">\t\t\t\t\t\t\t\t<\/h5>\t                            \t<div class=\"cs-info-box-text\"><p>Tropical luxury in the Pacific islands with exclusive over-water bungalows and villas at our 5-star hotel<\/p><\/div>\t                        <\/div>\t                    <\/div>\n                    <\/div>                    <div class=\"cs-info-box-item elementor-repeater-item-e253a92\">\n                    \t<div class=\"cs-item-container\">\t                        <div class=\"cs-info-box-img\"><i aria-hidden=\"true\" class=\"flaticon flaticon-sunrise\"><\/i>\t                        <\/div>\t                        <div class=\"cs-info-box-content\">\n\t                            <h5 class=\"cs-title cs-info-box-title\">\t\t\t\t\t\t\t\t<\/h5>\t                            \t<div class=\"cs-info-box-text\"><p>Wake up each morning to picturesque ocean or lagoon views from every hotel room<\/p><\/div>\t                        <\/div>\t                    <\/div>\n                    <\/div>                    <div class=\"cs-info-box-item elementor-repeater-item-03432c7\">\n                    \t<div class=\"cs-item-container\">\t                        <div class=\"cs-info-box-img\"><i aria-hidden=\"true\" class=\"flaticon flaticon-bathtub-5\"><\/i>\t                        <\/div>\t                        <div class=\"cs-info-box-content\">\n\t                            <h5 class=\"cs-title cs-info-box-title\">\t\t\t\t\t\t\t\t<\/h5>\t                            \t<div class=\"cs-info-box-text\"><p>All of our bungalows boast sleek bathrooms with soaking tubs, separate showers and premium amenities<\/p><\/div>\t                        <\/div>\t                    <\/div>\n                    <\/div>                    <div class=\"cs-info-box-item elementor-repeater-item-6d9a7a6\">\n                    \t<div class=\"cs-item-container\">\t                        <div class=\"cs-info-box-img\"><i aria-hidden=\"true\" class=\"flaticon flaticon-cocktail-1\"><\/i>\t                        <\/div>\t                        <div class=\"cs-info-box-content\">\n\t                            <h5 class=\"cs-title cs-info-box-title\">\t\t\t\t\t\t\t\t<\/h5>\t                            \t<div class=\"cs-info-box-text\"><p>Enjoy coffee or cocktails whilst relaxing on your bungalow's private deck overlooking the water<\/p><\/div>\t                        <\/div>\t                    <\/div>\n                    <\/div>                    <div class=\"cs-info-box-item elementor-repeater-item-be97d74\">\n                    \t<div class=\"cs-item-container\">\t                        <div class=\"cs-info-box-img\"><i aria-hidden=\"true\" class=\"flaticon flaticon-customer-service\"><\/i>\t                        <\/div>\t                        <div class=\"cs-info-box-content\">\n\t                            <h5 class=\"cs-title cs-info-box-title\">\t\t\t\t\t\t\t\t<\/h5>\t                            \t<div class=\"cs-info-box-text\"><p>Experience authentic Fijian craftsmanship and modern hotel luxuries in our overwater bungalows<\/p><\/div>\t                        <\/div>\t                    <\/div>\n                    <\/div>                    <div class=\"cs-info-box-item elementor-repeater-item-957a5a7\">\n                    \t<div class=\"cs-item-container\">\t                        <div class=\"cs-info-box-img\"><i aria-hidden=\"true\" class=\"flaticon flaticon-massage\"><\/i>\t                        <\/div>\t                        <div class=\"cs-info-box-content\">\n\t                            <h5 class=\"cs-title cs-info-box-title\">\t\t\t\t\t\t\t\t<\/h5>\t                            \t<div class=\"cs-info-box-text\"><p>Upgrade your stay in our Fiji hotel for more spacious accommodation and adjoining rooms<\/p><\/div>\t                        <\/div>\t                    <\/div>\n                    <\/div>\t\t\t\t<\/div>\n\t\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>h\u00e9bergements VILLAS Bungalows Villas Parcelas ENTI\u00c8REMENT \u00c9QUIP\u00c9 Villas Dans nos villas, vous trouverez le confort dont vous avez besoin pour vos vacances en famille, enti\u00e8rement \u00e9quip\u00e9es pour devenir votre s\u00e9jour id\u00e9al afin que vous puissiez profiter de l&rsquo;exp\u00e9rience. Habitaciones Villas VILLA ROMULUS 3 6 5 1 ba\u00f1o Villa catalana situada en el centro del camping, &#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":7160,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-wide-content.php","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"cozystay_single_page_hide_site_header":"","cozystay_single_page_site_header_source":"","cozystay_single_page_custom_site_header":"0","cozystay_single_page_custom_sticky_site_header":"0","cozystay_single_page_hide_page_title":"","cozystay_single_page_header_section_size":"","cozystay_single_page_header_background_color":"","cozystay_single_page_header_background_position_x":"center","cozystay_single_page_header_background_position_y":"center","cozystay_single_page_header_background_size":"cover","cozystay_single_page_header_background_repeat":"off","cozystay_single_page_header_background_scroll":"on","cozystay_single_page_header_text_color":"","cozystay_single_page_header_show_breadcrumb":"","cozystay_single_page_site_footer_hide_main":"","cozystay_single_custom_site_footer_main_source":"","cozystay_single_custom_site_footer_main":"0","cozystay_single_page_site_footer_hide_above":"","cozystay_single_custom_site_footer_above_source":"","cozystay_single_custom_site_footer_above":"0","cozystay_single_page_site_footer_hide_instagram":"","cozystay_single_page_site_footer_hide_bottom":"","cozystay_single_custom_mobile_menu_source":"","cozystay_single_custom_mobile_menu":"0","cozystay_single_custom_mobile_menu_animation":"","cozystay_single_custom_mobile_menu_width":"","cozystay_single_custom_mobile_menu_custom_width":375,"footnotes":""},"class_list":["post-7331","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Villas - Playa Bara - Camping - Caravaning - Bungalows - Spa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.playabara.es\/fr\/hebergement\/villas\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Villas\" \/>\n<meta property=\"og:description\" content=\"h\u00e9bergements VILLAS Bungalows Villas Parcelas ENTI\u00c8REMENT \u00c9QUIP\u00c9 Villas Dans nos villas, vous trouverez le confort dont vous avez besoin pour vos vacances en famille, enti\u00e8rement \u00e9quip\u00e9es pour devenir votre s\u00e9jour id\u00e9al afin que vous puissiez profiter de l&rsquo;exp\u00e9rience. Habitaciones Villas VILLA ROMULUS 3 6 5 1 ba\u00f1o Villa catalana situada en el centro del camping, ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.playabara.es\/fr\/hebergement\/villas\/\" \/>\n<meta property=\"og:site_name\" content=\"Playa Bara - Camping - Caravaning - Bungalows - Spa\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-15T11:01:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-ROMULUS-1-scaled-1-780x585.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.playabara.es\\\/fr\\\/hebergement\\\/villas\\\/\",\"url\":\"https:\\\/\\\/www.playabara.es\\\/fr\\\/hebergement\\\/villas\\\/\",\"name\":\"Villas - Playa Bara - Camping - Caravaning - Bungalows - Spa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.playabara.es\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.playabara.es\\\/fr\\\/hebergement\\\/villas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.playabara.es\\\/fr\\\/hebergement\\\/villas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.playabara.es\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/VILLA-ROMULUS-1-scaled-1-780x585.jpg\",\"datePublished\":\"2024-01-30T23:06:26+00:00\",\"dateModified\":\"2024-05-15T11:01:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.playabara.es\\\/fr\\\/hebergement\\\/villas\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.playabara.es\\\/fr\\\/hebergement\\\/villas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.playabara.es\\\/fr\\\/hebergement\\\/villas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.playabara.es\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/VILLA-ROMULUS-1-scaled-1-780x585.jpg\",\"contentUrl\":\"https:\\\/\\\/www.playabara.es\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/VILLA-ROMULUS-1-scaled-1-780x585.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.playabara.es\\\/fr\\\/hebergement\\\/villas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.playabara.es\\\/fr\\\/accueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"H\u00e9bergement\",\"item\":\"https:\\\/\\\/www.playabara.es\\\/fr\\\/hebergement\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Villas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.playabara.es\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.playabara.es\\\/fr\\\/\",\"name\":\"Playa Bara - Camping - Caravaning - Bungalows - Spa\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.playabara.es\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Villas - Playa Bara - Camping - Caravaning - Bungalows - Spa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.playabara.es\/fr\/hebergement\/villas\/","og_locale":"fr_FR","og_type":"article","og_title":"Villas","og_description":"h\u00e9bergements VILLAS Bungalows Villas Parcelas ENTI\u00c8REMENT \u00c9QUIP\u00c9 Villas Dans nos villas, vous trouverez le confort dont vous avez besoin pour vos vacances en famille, enti\u00e8rement \u00e9quip\u00e9es pour devenir votre s\u00e9jour id\u00e9al afin que vous puissiez profiter de l&rsquo;exp\u00e9rience. Habitaciones Villas VILLA ROMULUS 3 6 5 1 ba\u00f1o Villa catalana situada en el centro del camping, ...","og_url":"https:\/\/www.playabara.es\/fr\/hebergement\/villas\/","og_site_name":"Playa Bara - Camping - Caravaning - Bungalows - Spa","article_modified_time":"2024-05-15T11:01:07+00:00","og_image":[{"url":"https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-ROMULUS-1-scaled-1-780x585.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.playabara.es\/fr\/hebergement\/villas\/","url":"https:\/\/www.playabara.es\/fr\/hebergement\/villas\/","name":"Villas - Playa Bara - Camping - Caravaning - Bungalows - Spa","isPartOf":{"@id":"https:\/\/www.playabara.es\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.playabara.es\/fr\/hebergement\/villas\/#primaryimage"},"image":{"@id":"https:\/\/www.playabara.es\/fr\/hebergement\/villas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-ROMULUS-1-scaled-1-780x585.jpg","datePublished":"2024-01-30T23:06:26+00:00","dateModified":"2024-05-15T11:01:07+00:00","breadcrumb":{"@id":"https:\/\/www.playabara.es\/fr\/hebergement\/villas\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.playabara.es\/fr\/hebergement\/villas\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.playabara.es\/fr\/hebergement\/villas\/#primaryimage","url":"https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-ROMULUS-1-scaled-1-780x585.jpg","contentUrl":"https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/VILLA-ROMULUS-1-scaled-1-780x585.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.playabara.es\/fr\/hebergement\/villas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.playabara.es\/fr\/accueil\/"},{"@type":"ListItem","position":2,"name":"H\u00e9bergement","item":"https:\/\/www.playabara.es\/fr\/hebergement\/"},{"@type":"ListItem","position":3,"name":"Villas"}]},{"@type":"WebSite","@id":"https:\/\/www.playabara.es\/fr\/#website","url":"https:\/\/www.playabara.es\/fr\/","name":"Playa Bara - Camping - Caravaning - Bungalows - Spa","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.playabara.es\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.playabara.es\/fr\/wp-json\/wp\/v2\/pages\/7331","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.playabara.es\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.playabara.es\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.playabara.es\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.playabara.es\/fr\/wp-json\/wp\/v2\/comments?post=7331"}],"version-history":[{"count":4,"href":"https:\/\/www.playabara.es\/fr\/wp-json\/wp\/v2\/pages\/7331\/revisions"}],"predecessor-version":[{"id":8522,"href":"https:\/\/www.playabara.es\/fr\/wp-json\/wp\/v2\/pages\/7331\/revisions\/8522"}],"up":[{"embeddable":true,"href":"https:\/\/www.playabara.es\/fr\/wp-json\/wp\/v2\/pages\/7160"}],"wp:attachment":[{"href":"https:\/\/www.playabara.es\/fr\/wp-json\/wp\/v2\/media?parent=7331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}