{"id":7590,"date":"2024-02-01T18:24:29","date_gmt":"2024-02-01T17:24:29","guid":{"rendered":"https:\/\/www.playabara.es\/travaille-avec-nous\/"},"modified":"2024-05-17T15:52:04","modified_gmt":"2024-05-17T13:52:04","slug":"travaille-avec-nous","status":"publish","type":"page","link":"https:\/\/www.playabara.es\/fr\/travaille-avec-nous\/","title":{"rendered":"TRAVAILLE AVEC NOUS"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"7590\" class=\"elementor elementor-7590 elementor-2777\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ca1656d elementor-section-height-min-height cs-section-content-fullwidth cs-parallax-on-scroll cs_scroll_y_100 elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"ca1656d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" data-cs-parallax-y=\"100\" style=\"background-image: none;\" data-cs-background-image=\"https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/03\/CONDICIONES-DE-RESERVA.jpeg\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6b2c1df dark-color\" data-id=\"6b2c1df\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ed3f97e elementor-widget elementor-widget-cs_title\" data-id=\"ed3f97e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"cs_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"cs-title-wrap text-center\">\t            <h1 class=\"cs-title\">\n\t                TRAVAILLE AVEC NOUS\t            <\/h1>\t            <div class=\"cs-title-text\">\n\t                <p>Nous recherchons des personnes impliqu\u00e9es et ayant une vocation pour le service \u00e0 la client\u00e8le.<\/p>\n\t            <\/div>        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dc86288 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dc86288\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3a93c3c\" data-id=\"3a93c3c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-09b223d elementor-widget elementor-widget-image\" data-id=\"09b223d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"204\" height=\"205\" src=\"https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/02\/trabaja_icon.png\" class=\"attachment-2048x2048 size-2048x2048 wp-image-7592\" alt=\"\" srcset=\"https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/02\/trabaja_icon.png 204w, https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/02\/trabaja_icon-150x150.png 150w\" sizes=\"(max-width: 204px) 100vw, 204px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-67df04a elementor-widget elementor-widget-cs_title\" data-id=\"67df04a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"cs_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"cs-title-wrap text-center\">\t            <div class=\"cs-subtitle-wrap\"><span class=\"cs-subtitle\">NOUS VOUS RECHERCHONS<\/span><\/div>\t            <h3 class=\"cs-title\">\n\t                FAITES PARTIE D'UNE ENTREPRISE LEADER\t            <\/h3>\t            <div class=\"cs-title-text\">\n\t                <p>Playa Bara, fond\u00e9e en 1970, a plus de 50 ans d&rsquo;histoire dans l&rsquo;accueil des campeurs dans une atmosph\u00e8re familiale et accueillante, r\u00e9compens\u00e9e comme l&rsquo;un des meilleurs campings de la Costa Daurada. Nous avons une client\u00e8le cible \u00e0 la fois nationale et internationale.<\/p>\n<p>Avec nous, vous aurez l&rsquo;opportunit\u00e9 de faire partie d&rsquo;une entreprise avec beaucoup d&rsquo;exp\u00e9rience dans le secteur.<\/p>\n<p>Apr\u00e8s avoir grandi au fil des ann\u00e9es, nous recherchons quelqu&rsquo;un comme vous pour rejoindre notre \u00e9quipe de professionnels. Si vous recherchez un emploi stable dans un bon environnement de travail et dans un environnement privil\u00e9gi\u00e9, nous vous attendons.<\/p>\n\t            <\/div>        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ac9ba41 elementor-section-full_width elementor-section-content-middle elementor-hidden-tablet elementor-hidden-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"ac9ba41\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a7e5270\" data-id=\"a7e5270\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a630739\" data-id=\"a630739\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1165b93 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1165b93\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-c8421f3\" data-id=\"c8421f3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ee636a2 elementor-widget elementor-widget-cs_title\" data-id=\"ee636a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"cs_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"cs-title-wrap text-left\">\t            <h5 class=\"cs-title\">\n\t                Envoyez votre CV\t            <\/h5>\t            <div class=\"cs-title-text\">\n\t                <p>Remplissez ce formulaire et envoyez-nous votre CV, de pr\u00e9f\u00e9rence au format PDF<\/p>\n\t            <\/div>        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d1eca60 elementor-widget elementor-widget-cs_form_cf7\" data-id=\"d1eca60\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"custom-form-bara\" data-widget_type=\"cs_form_cf7.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"cs-form-cf7 placeholder-normal\">\n                <div class=\"cs-form-cf7-wrap\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f12101-o1\" lang=\"fr-FR\" dir=\"ltr\" data-wpcf7-id=\"12101\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/fr\/wp-json\/wp\/v2\/pages\/7590#wpcf7-f12101-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulaire de contact\" enctype=\"multipart\/form-data\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"12101\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"fr_FR\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f12101-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<labe>Nom et pr\u00e9nom\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"name\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t<\/p>\n<\/labe>\n<labe>Courrier \u00e9lectronique\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"correoelectronico\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"correoelectronico\" \/><\/span>\n\t<\/p>\n\t<p><label>Joindre votre CV<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"pdfcv\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-file\" accept=\".pdf\" aria-invalid=\"false\" type=\"file\" name=\"pdfcv\" \/><\/span>\n\t<\/p>\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"recepcioncv\"><span class=\"wpcf7-form-control wpcf7-checkbox wpcf7-validates-as-required\"><span class=\"wpcf7-list-item first last\"><label><input type=\"checkbox\" name=\"recepcioncv[]\" value=\"J&#039;accepte la r\u00e9ception de mon CV\" \/><span class=\"wpcf7-list-item-label\">J&#039;accepte la r\u00e9ception de mon CV<\/span><\/label><\/span><\/span><\/span>\n\t<\/p>\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"politicas\"><span class=\"wpcf7-form-control wpcf7-checkbox wpcf7-validates-as-required\"><span class=\"wpcf7-list-item first last\"><label><input type=\"checkbox\" name=\"politicas[]\" value=\"J&#039;ai lu et j&#039;accepte les politiques de confidentialit\u00e9\" \/><span class=\"wpcf7-list-item-label\">J&#039;ai lu et j&#039;accepte les politiques de confidentialit\u00e9<\/span><\/label><\/span><\/span><\/span>\n\t<\/p>\n\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Envoyer\" \/>\n\t<\/p>\n<\/labe><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/div>\n            <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-21f13ce e-con-full e-flex e-con e-parent\" data-id=\"21f13ce\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8aacd02 elementor-widget-divider--view-line_text elementor-widget-divider--element-align-center elementor-widget elementor-widget-divider\" data-id=\"8aacd02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<h6 class=\"elementor-divider__text elementor-divider__element\">\n\t\t\t\tOffres d'emploi\t\t\t\t<\/h6>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-765dd1b custom-job-loop e-flex e-con-boxed e-con e-parent\" data-id=\"765dd1b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4a7fc00 elementor-widget elementor-widget-shortcode\" data-id=\"4a7fc00\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"sjb-page\">\r\n<!-- Start: Jobs Listing Wrapper -->\r\n\r\n\r\n<!-- Start Job Filters\r\n================================================== -->\r\n<div class=\"sjb-filters sjb-filters-v1\">\r\n        <form class=\"filters-form\" action=\"https:\/\/www.playabara.es\/fr\/travaille-avec-nous\/\" method=\"get\">\r\n        <div class=\"row\">\r\n            \r\n    <!-- Keywords Search-->    \r\n    <div class=\"sjb-search-keywords col-md-10 col-xs-12\">\r\n        <div class=\"form-group\">\r\n                        <label class=\"sr-only\" for=\"keywords\">Mots-cl\u00e9s<\/label>\r\n            <input type=\"text\" class=\"form-control\" value=\"\" placeholder=\"Mots-cl\u00e9s\" id=\"keywords\" name=\"search_keywords\">\r\n        <\/div>\r\n    <\/div>\r\n    <div class=\"sjb-search-button col-md-3 col-xs-12\"><input class=\"btn-search btn btn-primary\" value=\"&#xf002;\" type=\"submit\"><\/div>        <\/div>\r\n    <\/form>\r\n<\/div>\r\n<!-- ==================================================\r\nEnd Job Filters -->\r\n\r\n\r\n<div class=\"sjb-listing\">\r\n        <!-- start Jobs Listing: List View -->\r\n    <div class=\"list-view\">\r\n        \r\n    \n<!-- Start Jobs List View \n================================================== -->\n<div class=\"list-data\">\n    <div class=\"v1 sjb-job-12126\">   \n        \n        <!-- Jobs List view header -->\n        <header>\n            <div class=\"row\">\n                \r\n<!-- Start Company Logo\r\n================================================== -->\r\n<div class=\"col-md-1 col-sm-2 hidden-xs\">\r\n    <div class=\"company-logo\">\r\n        <a href=\"https:\/\/www.playabara.es\/fr\/feina\/aide-de-cuisine\/\"><img decoding=\"async\" src=\"https:\/\/www.playabara.es\/wp-content\/plugins\/simple-job-board\/public\/images\/company.png\" alt=\"\" class=\"sjb-img-responsive \" id=\"\"\/><\/a>\r\n    <\/div>\r\n<\/div>\r\n\r\n<!-- ==================================================\r\nEnd Company Logo -->\r\n\r\n    \n                <div class=\"col-md-11 col-sm-12\">\n                    <div class=\"row sjb-list-row\">\n\n                    <div class=\"col-md-5 col-sm-12\">\r\n    <div class=\"job-info\">\r\n        <h4>\r\n            <a href=\"https:\/\/www.playabara.es\/fr\/feina\/aide-de-cuisine\/\">\r\n                <span class=\"job-title\">Aide de cuisine<\/span>            <\/a>\r\n\r\n        <\/h4>\r\n            <\/div>\r\n<\/div>\r\n\r\n<!-- Start Job Type\r\n================================================== -->\r\n<div class=\"col-md-2 col-sm-4 col-xs-12\">    \r\n     \r\n<\/div>\r\n<!-- ==================================================\r\nEnd Job Type -->\r\n\r\n\r\n<!-- Start Job's Location\r\n================================================== -->\r\n<div class=\"col-md-2 col-sm-4 col-xs-12\">\r\n    <\/div>\r\n<!-- ==================================================\r\nEnd Job's Location -->\r\n\r\n\r\n<!-- Start Job Posted Date\r\n================================================== -->\r\n<div class=\"col-md-3 col-sm-4 col-xs-12\">\r\n            <div class=\"job-date\"><i class=\"fa  fa-calendar-check\"><\/i>Publi\u00e9 il y a 2 ans<\/div>\r\n    <\/div>\r\n<!-- ==================================================\r\nEnd Job Posted Date -->\r\n\r\n                        \n                    <\/div> \n                <\/div>\n            <\/div>\n        <\/header>\n\n        \r\n    <!-- View more content start\r\n    ================================= -->\r\n    \r\n<!-- View long content start \r\n================================================== -->\r\n<div class=\"sjb_more_content\" id=\"sjb_more_content_12126\">\r\n    \n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Si vous commencez votre carri\u00e8re en cuisine et souhaitez acqu\u00e9rir de l'exp\u00e9rience dans un environnement professionnel et dynamique, c'est votre opportunit\u00e9 ! Nous recherchons des personnes d\u00e9sireuses d'apprendre, responsables et ayant une attitude positive pour soutenir notre \u00e9quipe dans la pr\u00e9paration de d\u00e9licieux plats. <\/p>\n<\/blockquote>\n\n<h3 class=\"wp-block-heading\"><strong>Responsabilit\u00e9s:<\/strong><\/h3>\n\n<ul class=\"wp-block-list\">\n<li>Aider \u00e0 la pr\u00e9paration et au contr\u00f4le des ingr\u00e9dients du menu sous la supervision du chef.<\/li>\n\n\n\n<li>Respecter les r\u00e9glementations alimentaires, les allerg\u00e8nes et HACCP.<\/li>\n\n\n\n<li>Organiser le stockage et la conservation des aliments.<\/li>\n\n\n\n<li>Assurer la fra\u00eecheur et la qualit\u00e9 des produits.<\/li>\n\n\n\n<li>Participer \u00e0 la pr\u00e9paration des plats, y compris des paellas, salades, desserts et plats grill\u00e9s pour viandes et poissons.<\/li>\n\n\n\n<li>Garantir la propret\u00e9, la s\u00e9curit\u00e9 et l'hygi\u00e8ne \u00e0 votre poste de travail.<\/li>\n\n\n\n<li>Assurer le bon usage, le respect et l'entretien de tout le mat\u00e9riel.<\/li>\n\n\n\n<li>Collaborer \u00e0 la gestion quotidienne des stocks et r\u00e9aliser des inventaires.<\/li>\n\n\n\n<li>Aider \u00e0 l'organisation et \u00e0 la conservation des aliments.<\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<h3 class=\"wp-block-heading\"><strong>Exigences:<\/strong><\/h3>\n\n<ul class=\"wp-block-list\">\n<li>Qualification minimale: CAP cuisine ou \u00e9quivalent.<\/li>\n\n\n\n<li>Autres dipl\u00f4mes, certifications et permis bienvenus.<\/li>\n\n\n\n<li>Minimum 1 \u00e0 2 ans d'exp\u00e9rience dans un poste similaire.<\/li>\n\n\n\n<li>Initiative et capacit\u00e9 \u00e0 favoriser un bon environnement de travail.<\/li>\n\n\n\n<li>Excellentes comp\u00e9tences en travail d'\u00e9quipe et attention aux d\u00e9tails.<\/li>\n\n\n\n<li>Mentalit\u00e9 positive, apprentissage constant et engagement.<\/li>\n\n\n\n<li>Flexibilit\u00e9 pour travailler en horaires de rotation, y compris les week-ends et les jours f\u00e9ri\u00e9s.<\/li>\n\n\n\n<li>Mobilit\u00e9 et permis de conduire indispensables.<\/li>\n<\/ul>\n\n<h3 class=\"wp-block-heading\"><strong>Nous offrons:<\/strong><\/h3>\n\n<ul class=\"wp-block-list\">\n<li>Contrat \u00e0 temps plein.<\/li>\n\n\n\n<li>Horaires de lundi \u00e0 dimanche avec des services fixes ou rotatifs et des jours de repos respectifs.<\/li>\n\n\n\n<li>Un environnement de travail agr\u00e9able et collaboratif.<\/li>\n\n\n\n<li>Opportunit\u00e9s de d\u00e9veloppement et de croissance professionnelle.<\/li>\n\n\n\n<li>R\u00e9mun\u00e9ration comp\u00e9titive.<\/li>\n<\/ul>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Si vous \u00eates pr\u00eat\/e \u00e0 commencer votre carri\u00e8re en cuisine et \u00eates motiv\u00e9\/e \u00e0 faire partie d'une \u00e9quipe qui valorise l'excellence et le d\u00e9veloppement professionnel, envoyez-nous votre CV et rejoignez-nous au Camping Playa Bara. C'est la premi\u00e8re \u00e9tape vers un avenir brillant dans la gastronomie! <\/p>\n<\/blockquote>\n\n<p class=\"wp-block-paragraph\"><\/p>\n    \r\n<!-- Start Job Features\r\n================================================== -->\r\n<div class=\"job-features\">\r\n    \r\n    <table class=\"table\">\r\n        <tbody>\r\n            \r\n                        <\/tbody>\r\n    <\/table>\r\n<\/div>\r\n<!-- ==================================================\r\nEnd Job Features -->\r\n\r\n<div class=\"clearfix\"><\/div>\r\n<\/div>\r\n<!-- ==================================================\r\nView long content end  -->\r\n\r\n    <!-- View more content end\r\n    ================================= -->\r\n\r\n    <!-- Start Job Short Description \r\n    ================================================== -->\r\n    <div class=\"job-description\">\r\n        <div id=\"sjb_less_content_12126\"><p>Si vous commencez votre carri\u00e8re en cuisine et souhaitez acqu\u00e9rir de l&rsquo;exp\u00e9rience dans un environnement professionnel et dynamique, c&rsquo;est votre opportunit\u00e9 ! Nous recherchons des perso...<\/p><\/div><div class=\"sjb-apply-now-btn\"><p><p><a href=\"javascript:void(0)\" id=\"quick-apply-btn\" class=\"btn btn-primary \" job_id=\"12126\">Quick Apply <\/a><a href=\"https:\/\/www.playabara.es\/fr\/feina\/aide-de-cuisine\/\" class=\"btn btn-primary \">En savoir plus<\/a><\/p><div class=\"sjb-view-less-btn\" id=\"sjb_view_less_btn_12126\"><a data-id=\"12126\" class=\"sjb_view_less_btn sjb_view_more_btn\">View less<\/a><\/div><\/p><\/div>    <\/div>\r\n    <!-- ==================================================\r\n    End Job Short Description  -->\r\n\r\n        <\/div>\n<\/div>\n<!-- ==================================================\nEnd Jobs List View -->\n\n<div class=\"clearfix\"><\/div>\n\n\n<!-- Start Jobs List View \n================================================== -->\n<div class=\"list-data\">\n    <div class=\"v1 sjb-job-12121\">   \n        \n        <!-- Jobs List view header -->\n        <header>\n            <div class=\"row\">\n                \r\n<!-- Start Company Logo\r\n================================================== -->\r\n<div class=\"col-md-1 col-sm-2 hidden-xs\">\r\n    <div class=\"company-logo\">\r\n        <a href=\"https:\/\/www.playabara.es\/fr\/feina\/commis-de-serveur-serveuse\/\"><img decoding=\"async\" src=\"https:\/\/www.playabara.es\/wp-content\/plugins\/simple-job-board\/public\/images\/company.png\" alt=\"\" class=\"sjb-img-responsive \" id=\"\"\/><\/a>\r\n    <\/div>\r\n<\/div>\r\n\r\n<!-- ==================================================\r\nEnd Company Logo -->\r\n\r\n    \n                <div class=\"col-md-11 col-sm-12\">\n                    <div class=\"row sjb-list-row\">\n\n                    <div class=\"col-md-5 col-sm-12\">\r\n    <div class=\"job-info\">\r\n        <h4>\r\n            <a href=\"https:\/\/www.playabara.es\/fr\/feina\/commis-de-serveur-serveuse\/\">\r\n                <span class=\"job-title\">Commis de serveur\/serveuse<\/span>            <\/a>\r\n\r\n        <\/h4>\r\n            <\/div>\r\n<\/div>\r\n\r\n<!-- Start Job Type\r\n================================================== -->\r\n<div class=\"col-md-2 col-sm-4 col-xs-12\">    \r\n     \r\n<\/div>\r\n<!-- ==================================================\r\nEnd Job Type -->\r\n\r\n\r\n<!-- Start Job's Location\r\n================================================== -->\r\n<div class=\"col-md-2 col-sm-4 col-xs-12\">\r\n    <\/div>\r\n<!-- ==================================================\r\nEnd Job's Location -->\r\n\r\n\r\n<!-- Start Job Posted Date\r\n================================================== -->\r\n<div class=\"col-md-3 col-sm-4 col-xs-12\">\r\n            <div class=\"job-date\"><i class=\"fa  fa-calendar-check\"><\/i>Publi\u00e9 il y a 2 ans<\/div>\r\n    <\/div>\r\n<!-- ==================================================\r\nEnd Job Posted Date -->\r\n\r\n                        \n                    <\/div> \n                <\/div>\n            <\/div>\n        <\/header>\n\n        \r\n    <!-- View more content start\r\n    ================================= -->\r\n    \r\n<!-- View long content start \r\n================================================== -->\r\n<div class=\"sjb_more_content\" id=\"sjb_more_content_12121\">\r\n    \n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Si vous d\u00e9butez votre carri\u00e8re dans l'h\u00f4tellerie et souhaitez acqu\u00e9rir de l'exp\u00e9rience dans un environnement professionnel et dynamique, c'est votre chance ! Nous recherchons des personnes d\u00e9sireuses d'apprendre, responsables et avec une attitude positive pour offrir un excellent service \u00e0 nos clients. <\/p>\n<\/blockquote>\n\n<h3 class=\"wp-block-heading\"><strong>Responsabilit\u00e9s:<\/strong><\/h3>\n\n<ul class=\"wp-block-list\">\n<li>Pr\u00e9parer et maintenir les zones de travail, les \u00e9quipements et les ustensiles en bon \u00e9tat.<\/li>\n\n\n\n<li>G\u00e9rer la facturation et les paiements en utilisant notre propre logiciel.<\/li>\n\n\n\n<li>Suivre les protocoles de r\u00e9ception, d'attention et de d\u00e9part des clients.<\/li>\n\n\n\n<li>Servir des boissons avec professionnalisme, g\u00e9rer les inventaires et maintenir les stocks de boissons bien approvisionn\u00e9s.<\/li>\n\n\n\n<li>Expliquer le menu et faire des suggestions de plats, boissons et vins aux clients.<\/li>\n\n\n\n<li>Collaborer \u00e0 la mise en place et au service d'\u00e9v\u00e9nements sp\u00e9ciaux.<\/li>\n\n\n\n<li>Maintenir la propret\u00e9 et l'ordre dans la zone de travail, cr\u00e9ant un environnement agr\u00e9able.<\/li>\n\n\n\n<li>Respecter les normes de qualit\u00e9, de l'environnement et de s\u00e9curit\u00e9 au travail.<\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<h3 class=\"wp-block-heading\"><strong>Exigences:<\/strong><\/h3>\n\n<ul class=\"wp-block-list\">\n<li>Qualification minimale: Bac professionnel en h\u00f4tellerie ou \u00e9quivalent de \u00e9coles priv\u00e9es d'h\u00f4tellerie.<\/li>\n\n\n\n<li>Minimum 1 an d'exp\u00e9rience dans des postes similaires.<\/li>\n\n\n\n<li>Bon niveau d'anglais indispensable; allemand et\/ou n\u00e9erlandais est un plus.<\/li>\n\n\n\n<li>Connaissances en gastronomie et cocktails tr\u00e8s appr\u00e9ci\u00e9es.<\/li>\n\n\n\n<li>Autres dipl\u00f4mes, certifications et permis bienvenus.<\/li>\n\n\n\n<li>Capacit\u00e9 \u00e0 travailler en \u00e9quipe, attention aux d\u00e9tails et orient\u00e9 client.<\/li>\n\n\n\n<li>Initiative et capacit\u00e9 \u00e0 favoriser un bon environnement de travail.<\/li>\n\n\n\n<li>Flexibilit\u00e9 pour travailler en horaires de rotation, y compris les week-ends et les jours f\u00e9ri\u00e9s.<\/li>\n\n\n\n<li>Mobilit\u00e9 et permis de conduire indispensables.<\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<h3 class=\"wp-block-heading\"><strong>Nous offrons:<\/strong><\/h3>\n\n<ul class=\"wp-block-list\">\n<li>Contrat \u00e0 temps plein.<\/li>\n\n\n\n<li>Horaires de lundi \u00e0 dimanche avec des services fixes ou rotatifs et des jours de repos respectifs.<\/li>\n\n\n\n<li>Un environnement de travail agr\u00e9able et collaboratif.<\/li>\n\n\n\n<li>Opportunit\u00e9s de d\u00e9veloppement et de croissance professionnelle.<\/li>\n\n\n\n<li>R\u00e9mun\u00e9ration comp\u00e9titive.<\/li>\n<\/ul>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Si vous \u00eates pr\u00eat \u00e0 relever un nouveau d\u00e9fi et \u00e0 commencer votre carri\u00e8re dans l'h\u00f4tellerie, envoyez-nous votre CV et rejoignez-nous au Camping Playa Bara!<\/p>\n<\/blockquote>\n\n<p class=\"wp-block-paragraph\"><\/p>\n    \r\n<!-- Start Job Features\r\n================================================== -->\r\n<div class=\"job-features\">\r\n    \r\n    <table class=\"table\">\r\n        <tbody>\r\n            \r\n                        <\/tbody>\r\n    <\/table>\r\n<\/div>\r\n<!-- ==================================================\r\nEnd Job Features -->\r\n\r\n<div class=\"clearfix\"><\/div>\r\n<\/div>\r\n<!-- ==================================================\r\nView long content end  -->\r\n\r\n    <!-- View more content end\r\n    ================================= -->\r\n\r\n    <!-- Start Job Short Description \r\n    ================================================== -->\r\n    <div class=\"job-description\">\r\n        <div id=\"sjb_less_content_12121\"><p>Si vous d\u00e9butez votre carri\u00e8re dans l&rsquo;h\u00f4tellerie et souhaitez acqu\u00e9rir de l&rsquo;exp\u00e9rience dans un environnement professionnel et dynamique, c&rsquo;est votre chance ! Nous recherchons de...<\/p><\/div><div class=\"sjb-apply-now-btn\"><p><p><a href=\"javascript:void(0)\" id=\"quick-apply-btn\" class=\"btn btn-primary \" job_id=\"12121\">Quick Apply <\/a><a href=\"https:\/\/www.playabara.es\/fr\/feina\/commis-de-serveur-serveuse\/\" class=\"btn btn-primary \">En savoir plus<\/a><\/p><div class=\"sjb-view-less-btn\" id=\"sjb_view_less_btn_12121\"><a data-id=\"12121\" class=\"sjb_view_less_btn sjb_view_more_btn\">View less<\/a><\/div><\/p><\/div>    <\/div>\r\n    <!-- ==================================================\r\n    End Job Short Description  -->\r\n\r\n        <\/div>\n<\/div>\n<!-- ==================================================\nEnd Jobs List View -->\n\n<div class=\"clearfix\"><\/div>\n\n\n<!-- Start Jobs List View \n================================================== -->\n<div class=\"list-data\">\n    <div class=\"v1 sjb-job-12138\">   \n        \n        <!-- Jobs List view header -->\n        <header>\n            <div class=\"row\">\n                \r\n<!-- Start Company Logo\r\n================================================== -->\r\n<div class=\"col-md-1 col-sm-2 hidden-xs\">\r\n    <div class=\"company-logo\">\r\n        <a href=\"https:\/\/www.playabara.es\/fr\/feina\/serveur-serveuse\/\"><img decoding=\"async\" src=\"https:\/\/www.playabara.es\/wp-content\/plugins\/simple-job-board\/public\/images\/company.png\" alt=\"\" class=\"sjb-img-responsive \" id=\"\"\/><\/a>\r\n    <\/div>\r\n<\/div>\r\n\r\n<!-- ==================================================\r\nEnd Company Logo -->\r\n\r\n    \n                <div class=\"col-md-11 col-sm-12\">\n                    <div class=\"row sjb-list-row\">\n\n                    <div class=\"col-md-5 col-sm-12\">\r\n    <div class=\"job-info\">\r\n        <h4>\r\n            <a href=\"https:\/\/www.playabara.es\/fr\/feina\/serveur-serveuse\/\">\r\n                <span class=\"job-title\">Serveur\/Serveuse<\/span>            <\/a>\r\n\r\n        <\/h4>\r\n            <\/div>\r\n<\/div>\r\n\r\n<!-- Start Job Type\r\n================================================== -->\r\n<div class=\"col-md-2 col-sm-4 col-xs-12\">    \r\n     \r\n<\/div>\r\n<!-- ==================================================\r\nEnd Job Type -->\r\n\r\n\r\n<!-- Start Job's Location\r\n================================================== -->\r\n<div class=\"col-md-2 col-sm-4 col-xs-12\">\r\n    <\/div>\r\n<!-- ==================================================\r\nEnd Job's Location -->\r\n\r\n\r\n<!-- Start Job Posted Date\r\n================================================== -->\r\n<div class=\"col-md-3 col-sm-4 col-xs-12\">\r\n            <div class=\"job-date\"><i class=\"fa  fa-calendar-check\"><\/i>Publi\u00e9 il y a 2 ans<\/div>\r\n    <\/div>\r\n<!-- ==================================================\r\nEnd Job Posted Date -->\r\n\r\n                        \n                    <\/div> \n                <\/div>\n            <\/div>\n        <\/header>\n\n        \r\n    <!-- View more content start\r\n    ================================= -->\r\n    \r\n<!-- View long content start \r\n================================================== -->\r\n<div class=\"sjb_more_content\" id=\"sjb_more_content_12138\">\r\n    \n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Nous souhaitons trouver des personnes professionnelles, passionn\u00e9es par l'h\u00f4tellerie et capables d'offrir un service exceptionnel. Nous valorisons l'int\u00e9grit\u00e9, la responsabilit\u00e9 et l'engagement. Si vous \u00eates passionn\u00e9 par le contact avec les clients et souhaitez rejoindre notre \u00e9quipe, nous vous voulons avec nous!  <\/p>\n<\/blockquote>\n\n<h3 class=\"wp-block-heading\"><strong>Responsabilit\u00e9s:<\/strong><\/h3>\n\n<ul class=\"wp-block-list\">\n<li>Pr\u00e9parer et maintenir les zones de travail, les \u00e9quipements et les ustensiles en bon \u00e9tat.<\/li>\n\n\n\n<li>Effectuer les t\u00e2ches de facturation et de recouvrement \u00e0 l'aide de notre programme informatique.<\/li>\n\n\n\n<li>Suivre les protocoles de r\u00e9ception, d'attention et de d\u00e9part des clients.<\/li>\n\n\n\n<li>Servir des boissons avec professionnalisme, g\u00e9rer les inventaires et maintenir les stocks de boissons bien approvisionn\u00e9s.<\/li>\n\n\n\n<li>Pr\u00e9senter le menu, faire des suggestions de plats, de boissons et de vins.<\/li>\n\n\n\n<li>Participer \u00e0 l'installation et au service d'\u00e9v\u00e9nements sp\u00e9ciaux.<\/li>\n\n\n\n<li>Maintenir la propret\u00e9 et l'ordre dans la zone de travail, cr\u00e9ant un environnement agr\u00e9able.<\/li>\n\n\n\n<li>Respecter les normes de qualit\u00e9, d'environnement et de pr\u00e9vention des risques professionnels.<\/li>\n\n\n\n<li>Ma\u00eetriser le bar et le plateau de service avec dext\u00e9rit\u00e9, garantissant un service fluide. Si vous \u00eates pr\u00eat(e) \u00e0 relever un nouveau.<\/li>\n<\/ul>\n\n<h3 class=\"wp-block-heading\"><strong>Exigences:<\/strong><\/h3>\n\n<ul class=\"wp-block-list\">\n<li>Qualification minimale: Bac Pro en services de restauration ou dipl\u00f4mes priv\u00e9s d'\u00e9coles h\u00f4teli\u00e8res.<\/li>\n\n\n\n<li>Exp\u00e9rience minimale de 2 ans dans des postes similaires.<\/li>\n\n\n\n<li>Un bon niveau d'anglais, d'allemand et\/ou de n\u00e9erlandais est appr\u00e9ci\u00e9.<\/li>\n\n\n\n<li>Connaissances appr\u00e9ci\u00e9es en gastronomie et cocktails.<\/li>\n\n\n\n<li>Autres dipl\u00f4mes, certifications et permis bienvenus.<\/li>\n\n\n\n<li>Capacit\u00e9 \u00e0 travailler en \u00e9quipe, attention aux d\u00e9tails et orientation client.<\/li>\n\n\n\n<li>Initiative et capacit\u00e9 \u00e0 favoriser un bon environnement de travail.<\/li>\n\n\n\n<li>Flexibilit\u00e9 pour travailler en rotation, y compris les week-ends et jours f\u00e9ri\u00e9s.<\/li>\n\n\n\n<li>Mobilit\u00e9 et permis de conduire indispensables.<\/li>\n<\/ul>\n\n<h3 class=\"wp-block-heading\"><strong>Nous offrons:<\/strong><\/h3>\n\n<ul class=\"wp-block-list\">\n<li>Contrat \u00e0 temps plein.<\/li>\n\n\n\n<li>Horaires de lundi \u00e0 dimanche avec des services fixes ou rotatifs et des jours de repos respectifs.<\/li>\n\n\n\n<li>Un environnement de travail agr\u00e9able et collaboratif.<\/li>\n\n\n\n<li>Opportunit\u00e9s de d\u00e9veloppement et de croissance professionnelle.<\/li>\n\n\n\n<li>R\u00e9mun\u00e9ration comp\u00e9titive.<\/li>\n<\/ul>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Si vous \u00eates pr\u00eat(e) \u00e0 relever un nouveau d\u00e9fi et souhaitez faire partie d'une \u00e9quipe engag\u00e9e dans l'excellence du service, envoyez-nous votre CV et rejoignez-nous au Camping Playa Bara!<\/p>\n<\/blockquote>\n    \r\n<!-- Start Job Features\r\n================================================== -->\r\n<div class=\"job-features\">\r\n    \r\n    <table class=\"table\">\r\n        <tbody>\r\n            \r\n                        <\/tbody>\r\n    <\/table>\r\n<\/div>\r\n<!-- ==================================================\r\nEnd Job Features -->\r\n\r\n<div class=\"clearfix\"><\/div>\r\n<\/div>\r\n<!-- ==================================================\r\nView long content end  -->\r\n\r\n    <!-- View more content end\r\n    ================================= -->\r\n\r\n    <!-- Start Job Short Description \r\n    ================================================== -->\r\n    <div class=\"job-description\">\r\n        <div id=\"sjb_less_content_12138\"><p>Nous souhaitons trouver des personnes professionnelles, passionn\u00e9es par l&rsquo;h\u00f4tellerie et capables d&rsquo;offrir un service exceptionnel. Nous valorisons l&rsquo;int\u00e9grit\u00e9, la responsabilit\u00e9...<\/p><\/div><div class=\"sjb-apply-now-btn\"><p><p><a href=\"javascript:void(0)\" id=\"quick-apply-btn\" class=\"btn btn-primary \" job_id=\"12138\">Quick Apply <\/a><a href=\"https:\/\/www.playabara.es\/fr\/feina\/serveur-serveuse\/\" class=\"btn btn-primary \">En savoir plus<\/a><\/p><div class=\"sjb-view-less-btn\" id=\"sjb_view_less_btn_12138\"><a data-id=\"12138\" class=\"sjb_view_less_btn sjb_view_more_btn\">View less<\/a><\/div><\/p><\/div>    <\/div>\r\n    <!-- ==================================================\r\n    End Job Short Description  -->\r\n\r\n        <\/div>\n<\/div>\n<!-- ==================================================\nEnd Jobs List View -->\n\n<div class=\"clearfix\"><\/div>\n\n\n<!-- Start Jobs List View \n================================================== -->\n<div class=\"list-data\">\n    <div class=\"v1 sjb-job-12143\">   \n        \n        <!-- Jobs List view header -->\n        <header>\n            <div class=\"row\">\n                \r\n<!-- Start Company Logo\r\n================================================== -->\r\n<div class=\"col-md-1 col-sm-2 hidden-xs\">\r\n    <div class=\"company-logo\">\r\n        <a href=\"https:\/\/www.playabara.es\/fr\/feina\/cuisinier-ere\/\"><img decoding=\"async\" src=\"https:\/\/www.playabara.es\/wp-content\/plugins\/simple-job-board\/public\/images\/company.png\" alt=\"\" class=\"sjb-img-responsive \" id=\"\"\/><\/a>\r\n    <\/div>\r\n<\/div>\r\n\r\n<!-- ==================================================\r\nEnd Company Logo -->\r\n\r\n    \n                <div class=\"col-md-11 col-sm-12\">\n                    <div class=\"row sjb-list-row\">\n\n                    <div class=\"col-md-5 col-sm-12\">\r\n    <div class=\"job-info\">\r\n        <h4>\r\n            <a href=\"https:\/\/www.playabara.es\/fr\/feina\/cuisinier-ere\/\">\r\n                <span class=\"job-title\">Cuisinier\/\u00e8re<\/span>            <\/a>\r\n\r\n        <\/h4>\r\n            <\/div>\r\n<\/div>\r\n\r\n<!-- Start Job Type\r\n================================================== -->\r\n<div class=\"col-md-2 col-sm-4 col-xs-12\">    \r\n     \r\n<\/div>\r\n<!-- ==================================================\r\nEnd Job Type -->\r\n\r\n\r\n<!-- Start Job's Location\r\n================================================== -->\r\n<div class=\"col-md-2 col-sm-4 col-xs-12\">\r\n    <\/div>\r\n<!-- ==================================================\r\nEnd Job's Location -->\r\n\r\n\r\n<!-- Start Job Posted Date\r\n================================================== -->\r\n<div class=\"col-md-3 col-sm-4 col-xs-12\">\r\n            <div class=\"job-date\"><i class=\"fa  fa-calendar-check\"><\/i>Publi\u00e9 il y a 2 ans<\/div>\r\n    <\/div>\r\n<!-- ==================================================\r\nEnd Job Posted Date -->\r\n\r\n                        \n                    <\/div> \n                <\/div>\n            <\/div>\n        <\/header>\n\n        \r\n    <!-- View more content start\r\n    ================================= -->\r\n    \r\n<!-- View long content start \r\n================================================== -->\r\n<div class=\"sjb_more_content\" id=\"sjb_more_content_12143\">\r\n    \n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Nous recherchons un(e) cuisinier\/\u00e8re professionnel(le) et passionn\u00e9(e) par la gastronomie pour rejoindre notre \u00e9quipe au Camping Playa Bara. Si vous appr\u00e9ciez la qualit\u00e9, la cr\u00e9ativit\u00e9 et l'engagement, et aimez travailler en \u00e9quipe, nous vous voulons avec nous! <\/p>\n<\/blockquote>\n\n<h3 class=\"wp-block-heading\"><strong>Responsabilit\u00e9s:<\/strong><\/h3>\n\n<ul class=\"wp-block-list\">\n<li>Pr\u00e9parer et contr\u00f4ler les ingr\u00e9dients du menu sous votre charge, en veillant au respect des ordres du chef.<\/li>\n\n\n\n<li>Respecter les r\u00e9glementations alimentaires, les allerg\u00e8nes et HACCP.<\/li>\n\n\n\n<li>Organiser le stockage et la conservation des aliments.<\/li>\n\n\n\n<li>Assurer la fra\u00eecheur et la qualit\u00e9 des produits.<\/li>\n\n\n\n<li>Avoir de l'exp\u00e9rience dans la pr\u00e9paration de paellas.<\/li>\n\n\n\n<li>Garantir la propret\u00e9, la s\u00e9curit\u00e9 et l'hygi\u00e8ne \u00e0 votre poste de travail.<\/li>\n\n\n\n<li>Assurer le bon usage, le respect et l'entretien de tout le mat\u00e9riel.<\/li>\n\n\n\n<li>Participer \u00e0 la gestion quotidienne des stocks.<\/li>\n<\/ul>\n\n<h3 class=\"wp-block-heading\"><strong>Exigences:<\/strong><\/h3>\n\n<ul class=\"wp-block-list\">\n<li>Qualification minimale: Dipl\u00f4me professionnel interm\u00e9diaire ou sup\u00e9rieur en gastronomie ou cuisine.<\/li>\n\n\n\n<li>Autres dipl\u00f4mes, certifications et permis bienvenus.<\/li>\n\n\n\n<li>Exp\u00e9rience minimale de 3 ans dans des postes similaires.<\/li>\n\n\n\n<li>Cr\u00e9ativit\u00e9 culinaire et dext\u00e9rit\u00e9 manuelle.<\/li>\n\n\n\n<li>Connaissances solides en s\u00e9curit\u00e9 alimentaire, gestion des allerg\u00e8nes et HACCP.<\/li>\n\n\n\n<li>Capacit\u00e9 \u00e0 travailler en \u00e9quipe et de mani\u00e8re collaborative.<\/li>\n\n\n\n<li>Excellente attention aux d\u00e9tails et capacit\u00e9 \u00e0 travailler sous pression.<\/li>\n\n\n\n<li>Mentalit\u00e9 positive, apprentissage constant et engagement.<\/li>\n\n\n\n<li>Flexibilit\u00e9 pour travailler en rotation, y compris les week-ends et jours f\u00e9ri\u00e9s.<\/li>\n\n\n\n<li>Mobilit\u00e9 et permis de conduire indispensables.<\/li>\n<\/ul>\n\n<h3 class=\"wp-block-heading\"><strong>Nous offrons:<\/strong><\/h3>\n\n<ul class=\"wp-block-list\">\n<li>Contrat \u00e0 temps plein.<\/li>\n\n\n\n<li>Horaires de lundi \u00e0 dimanche avec des services fixes ou rotatifs et des jours de repos respectifs.<\/li>\n\n\n\n<li>Un environnement de travail agr\u00e9able et collaboratif.<\/li>\n\n\n\n<li>Opportunit\u00e9s de d\u00e9veloppement et de croissance professionnelle.<\/li>\n\n\n\n<li>R\u00e9mun\u00e9ration comp\u00e9titive.<\/li>\n<\/ul>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Si vous \u00eates pr\u00eat(e) \u00e0 relever un nouveau d\u00e9fi et \u00e0 faire partie d'une \u00e9quipe engag\u00e9e dans l'excellence culinaire, envoyez-nous votre CV et rejoignez-nous au Camping Playa Bara!<\/p>\n<\/blockquote>\n\n<p class=\"wp-block-paragraph\"><\/p>\n    \r\n<!-- Start Job Features\r\n================================================== -->\r\n<div class=\"job-features\">\r\n    \r\n    <table class=\"table\">\r\n        <tbody>\r\n            \r\n                        <\/tbody>\r\n    <\/table>\r\n<\/div>\r\n<!-- ==================================================\r\nEnd Job Features -->\r\n\r\n<div class=\"clearfix\"><\/div>\r\n<\/div>\r\n<!-- ==================================================\r\nView long content end  -->\r\n\r\n    <!-- View more content end\r\n    ================================= -->\r\n\r\n    <!-- Start Job Short Description \r\n    ================================================== -->\r\n    <div class=\"job-description\">\r\n        <div id=\"sjb_less_content_12143\"><p>Nous recherchons un(e) cuisinier\/\u00e8re professionnel(le) et passionn\u00e9(e) par la gastronomie pour rejoindre notre \u00e9quipe au Camping Playa Bara. Si vous appr\u00e9ciez la qualit\u00e9, la cr\u00e9ativit\u00e9 et l&rsq...<\/p><\/div><div class=\"sjb-apply-now-btn\"><p><p><a href=\"javascript:void(0)\" id=\"quick-apply-btn\" class=\"btn btn-primary \" job_id=\"12143\">Quick Apply <\/a><a href=\"https:\/\/www.playabara.es\/fr\/feina\/cuisinier-ere\/\" class=\"btn btn-primary \">En savoir plus<\/a><\/p><div class=\"sjb-view-less-btn\" id=\"sjb_view_less_btn_12143\"><a data-id=\"12143\" class=\"sjb_view_less_btn sjb_view_more_btn\">View less<\/a><\/div><\/p><\/div>    <\/div>\r\n    <!-- ==================================================\r\n    End Job Short Description  -->\r\n\r\n        <\/div>\n<\/div>\n<!-- ==================================================\nEnd Jobs List View -->\n\n<div class=\"clearfix\"><\/div>\n\n\n<!-- Start Jobs List View \n================================================== -->\n<div class=\"list-data\">\n    <div class=\"v1 sjb-job-12161\">   \n        \n        <!-- Jobs List view header -->\n        <header>\n            <div class=\"row\">\n                \r\n<!-- Start Company Logo\r\n================================================== -->\r\n<div class=\"col-md-1 col-sm-2 hidden-xs\">\r\n    <div class=\"company-logo\">\r\n        <a href=\"https:\/\/www.playabara.es\/fr\/feina\/jardinier-jardiniere\/\"><img decoding=\"async\" src=\"https:\/\/www.playabara.es\/wp-content\/plugins\/simple-job-board\/public\/images\/company.png\" alt=\"\" class=\"sjb-img-responsive \" id=\"\"\/><\/a>\r\n    <\/div>\r\n<\/div>\r\n\r\n<!-- ==================================================\r\nEnd Company Logo -->\r\n\r\n    \n                <div class=\"col-md-11 col-sm-12\">\n                    <div class=\"row sjb-list-row\">\n\n                    <div class=\"col-md-5 col-sm-12\">\r\n    <div class=\"job-info\">\r\n        <h4>\r\n            <a href=\"https:\/\/www.playabara.es\/fr\/feina\/jardinier-jardiniere\/\">\r\n                <span class=\"job-title\">Jardinier\/Jardini\u00e8re<\/span>            <\/a>\r\n\r\n        <\/h4>\r\n            <\/div>\r\n<\/div>\r\n\r\n<!-- Start Job Type\r\n================================================== -->\r\n<div class=\"col-md-2 col-sm-4 col-xs-12\">    \r\n     \r\n<\/div>\r\n<!-- ==================================================\r\nEnd Job Type -->\r\n\r\n\r\n<!-- Start Job's Location\r\n================================================== -->\r\n<div class=\"col-md-2 col-sm-4 col-xs-12\">\r\n    <\/div>\r\n<!-- ==================================================\r\nEnd Job's Location -->\r\n\r\n\r\n<!-- Start Job Posted Date\r\n================================================== -->\r\n<div class=\"col-md-3 col-sm-4 col-xs-12\">\r\n            <div class=\"job-date\"><i class=\"fa  fa-calendar-check\"><\/i>Publi\u00e9 il y a 2 ans<\/div>\r\n    <\/div>\r\n<!-- ==================================================\r\nEnd Job Posted Date -->\r\n\r\n                        \n                    <\/div> \n                <\/div>\n            <\/div>\n        <\/header>\n\n        \r\n    <!-- View more content start\r\n    ================================= -->\r\n    \r\n<!-- View long content start \r\n================================================== -->\r\n<div class=\"sjb_more_content\" id=\"sjb_more_content_12161\">\r\n    \n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Nous recherchons un(e) jardinier\/jardini\u00e8re d\u00e9di\u00e9(e) et passionn\u00e9(e) pour maintenir et embellir notre environnement naturel. Si vous aimez travailler en plein air, avez des comp\u00e9tences en jardinage et souhaitez faire partie d'un environnement de travail positif, nous vous voulons dans notre \u00e9quipe! <\/p>\n<\/blockquote>\n\n<h3 class=\"wp-block-heading\"><strong>Responsabilit\u00e9s:<\/strong><\/h3>\n\n<ul class=\"wp-block-list\">\n<li>Entretenir et prendre soin des espaces verts du camping, y compris les pelouses, jardins et plantes.<\/li>\n\n\n\n<li>Effectuer des t\u00e2ches telles que la taille, l'arrosage et la fertilisation des plantes et arbres.<\/li>\n\n\n\n<li>Contr\u00f4ler les ravageurs et les maladies des plantes en utilisant des produits phytosanitaires appropri\u00e9s et respectueux de l'environnement.<\/li>\n\n\n\n<li>Planter des fleurs, arbres et arbustes, garantissant un environnement esth\u00e9tique et agr\u00e9able pour les clients.<\/li>\n\n\n\n<li>Garder les espaces ext\u00e9rieurs propres et bien ordonn\u00e9s.<\/li>\n\n\n\n<li>Superviser et maintenir en bon \u00e9tat l'\u00e9quipement de jardinage.<\/li>\n\n\n\n<li>Coordonner avec les autres d\u00e9partements pour s'assurer que les espaces verts r\u00e9pondent aux normes du camping.<\/li>\n<\/ul>\n\n<h3 class=\"wp-block-heading\"><strong>Exigences:<\/strong><\/h3>\n\n<ul class=\"wp-block-list\">\n<li>Exp\u00e9rience pr\u00e9alable en jardinage, de pr\u00e9f\u00e9rence dans les campings, h\u00f4tels ou parcs.<\/li>\n\n\n\n<li>Connaissance de l'utilisation des outils et des machines de jardinage.<\/li>\n\n\n\n<li>Connaissance de la lutte contre les ravageurs et de l'entretien des plantes.<\/li>\n\n\n\n<li>Personne responsable, minutieuse et en bonne condition physique.<\/li>\n\n\n\n<li>Capacit\u00e9 \u00e0 travailler en \u00e9quipe et de mani\u00e8re ind\u00e9pendante.<\/li>\n\n\n\n<li>Disponibilit\u00e9 pour travailler en horaires d\u00e9cal\u00e9s, y compris les week-ends et jours f\u00e9ri\u00e9s.<\/li>\n\n\n\n<li>Mobilit\u00e9 et permis de conduire indispensables.<\/li>\n<\/ul>\n\n<h3 class=\"wp-block-heading\"><strong>Nous offrons:<\/strong><\/h3>\n\n<ul class=\"wp-block-list\">\n<li>Contrat \u00e0 temps plein.<\/li>\n\n\n\n<li>Horaires de lundi \u00e0 dimanche avec des \u00e9quipes fixes ou rotatives et des jours de repos respectifs.<\/li>\n\n\n\n<li>Un environnement de travail agr\u00e9able et collaboratif.<\/li>\n\n\n\n<li>Opportunit\u00e9s de d\u00e9veloppement et de croissance professionnelle.<\/li>\n\n\n\n<li>R\u00e9mun\u00e9ration comp\u00e9titive.<\/li>\n<\/ul>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Si vous \u00eates pr\u00eat(e) pour un nouveau d\u00e9fi et souhaitez faire partie d'une \u00e9quipe engag\u00e9e et passionn\u00e9e, envoyez-nous votre CV et rejoignez-nous au Camping Playa Bara!<\/p>\n<\/blockquote>\n\n<p class=\"wp-block-paragraph\"><\/p>\n    \r\n<!-- Start Job Features\r\n================================================== -->\r\n<div class=\"job-features\">\r\n    \r\n    <table class=\"table\">\r\n        <tbody>\r\n            \r\n                        <\/tbody>\r\n    <\/table>\r\n<\/div>\r\n<!-- ==================================================\r\nEnd Job Features -->\r\n\r\n<div class=\"clearfix\"><\/div>\r\n<\/div>\r\n<!-- ==================================================\r\nView long content end  -->\r\n\r\n    <!-- View more content end\r\n    ================================= -->\r\n\r\n    <!-- Start Job Short Description \r\n    ================================================== -->\r\n    <div class=\"job-description\">\r\n        <div id=\"sjb_less_content_12161\"><p>Nous recherchons un(e) jardinier\/jardini\u00e8re d\u00e9di\u00e9(e) et passionn\u00e9(e) pour maintenir et embellir notre environnement naturel. Si vous aimez travailler en plein air, avez des comp\u00e9tences en jardina...<\/p><\/div><div class=\"sjb-apply-now-btn\"><p><p><a href=\"javascript:void(0)\" id=\"quick-apply-btn\" class=\"btn btn-primary \" job_id=\"12161\">Quick Apply <\/a><a href=\"https:\/\/www.playabara.es\/fr\/feina\/jardinier-jardiniere\/\" class=\"btn btn-primary \">En savoir plus<\/a><\/p><div class=\"sjb-view-less-btn\" id=\"sjb_view_less_btn_12161\"><a data-id=\"12161\" class=\"sjb_view_less_btn sjb_view_more_btn\">View less<\/a><\/div><\/p><\/div>    <\/div>\r\n    <!-- ==================================================\r\n    End Job Short Description  -->\r\n\r\n        <\/div>\n<\/div>\n<!-- ==================================================\nEnd Jobs List View -->\n\n<div class=\"clearfix\"><\/div>\n\n\r\n    <\/div> <!-- end Jobs Listing: List View -->\r\n<\/div>\r\n<!-- End: Jobs Listing -->\r\n\r\n<div class=\"clearfix\"><\/div>\r\n<\/div>\r\n<!-- End: Jobs Listing Wrapper -->\r\n\r\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>TRAVAILLE AVEC NOUS Nous recherchons des personnes impliqu\u00e9es et ayant une vocation pour le service \u00e0 la client\u00e8le. NOUS VOUS RECHERCHONS FAITES PARTIE D&rsquo;UNE ENTREPRISE LEADER Playa Bara, fond\u00e9e en 1970, a plus de 50 ans d&#8217;histoire dans l&#8217;accueil des campeurs dans une atmosph\u00e8re familiale et accueillante, r\u00e9compens\u00e9e comme l&#8217;un des meilleurs campings de la &#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"cozystay_single_page_hide_site_header":"","cozystay_single_page_site_header_source":"","cozystay_single_page_custom_site_header":"0","cozystay_single_page_custom_sticky_site_header":"0","cozystay_single_page_hide_page_title":"","cozystay_single_page_header_section_size":"","cozystay_single_page_header_background_color":"","cozystay_single_page_header_background_position_x":"center","cozystay_single_page_header_background_position_y":"center","cozystay_single_page_header_background_size":"cover","cozystay_single_page_header_background_repeat":"off","cozystay_single_page_header_background_scroll":"on","cozystay_single_page_header_text_color":"","cozystay_single_page_header_show_breadcrumb":"","cozystay_single_page_site_footer_hide_main":"","cozystay_single_custom_site_footer_main_source":"","cozystay_single_custom_site_footer_main":"0","cozystay_single_page_site_footer_hide_above":"","cozystay_single_custom_site_footer_above_source":"","cozystay_single_custom_site_footer_above":"0","cozystay_single_page_site_footer_hide_instagram":"","cozystay_single_page_site_footer_hide_bottom":"","cozystay_single_custom_mobile_menu_source":"","cozystay_single_custom_mobile_menu":"0","cozystay_single_custom_mobile_menu_animation":"","cozystay_single_custom_mobile_menu_width":"","cozystay_single_custom_mobile_menu_custom_width":375,"footnotes":""},"class_list":["post-7590","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>TRAVAILLE AVEC NOUS - Playa Bara - Camping - Caravaning - Bungalows - Spa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.playabara.es\/fr\/travaille-avec-nous\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TRAVAILLE AVEC NOUS\" \/>\n<meta property=\"og:description\" content=\"TRAVAILLE AVEC NOUS Nous recherchons des personnes impliqu\u00e9es et ayant une vocation pour le service \u00e0 la client\u00e8le. NOUS VOUS RECHERCHONS FAITES PARTIE D&rsquo;UNE ENTREPRISE LEADER Playa Bara, fond\u00e9e en 1970, a plus de 50 ans d&#8217;histoire dans l&#8217;accueil des campeurs dans une atmosph\u00e8re familiale et accueillante, r\u00e9compens\u00e9e comme l&#8217;un des meilleurs campings de la ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.playabara.es\/fr\/travaille-avec-nous\/\" \/>\n<meta property=\"og:site_name\" content=\"Playa Bara - Camping - Caravaning - Bungalows - Spa\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-17T13:52:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/02\/trabaja_icon.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.playabara.es\\\/fr\\\/travaille-avec-nous\\\/\",\"url\":\"https:\\\/\\\/www.playabara.es\\\/fr\\\/travaille-avec-nous\\\/\",\"name\":\"TRAVAILLE AVEC NOUS - Playa Bara - Camping - Caravaning - Bungalows - Spa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.playabara.es\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.playabara.es\\\/fr\\\/travaille-avec-nous\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.playabara.es\\\/fr\\\/travaille-avec-nous\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.playabara.es\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/trabaja_icon.png\",\"datePublished\":\"2024-02-01T17:24:29+00:00\",\"dateModified\":\"2024-05-17T13:52:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.playabara.es\\\/fr\\\/travaille-avec-nous\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.playabara.es\\\/fr\\\/travaille-avec-nous\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.playabara.es\\\/fr\\\/travaille-avec-nous\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.playabara.es\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/trabaja_icon.png\",\"contentUrl\":\"https:\\\/\\\/www.playabara.es\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/trabaja_icon.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.playabara.es\\\/fr\\\/travaille-avec-nous\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.playabara.es\\\/fr\\\/accueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TRAVAILLE AVEC NOUS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.playabara.es\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.playabara.es\\\/fr\\\/\",\"name\":\"Playa Bara - Camping - Caravaning - Bungalows - Spa\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.playabara.es\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"TRAVAILLE AVEC NOUS - Playa Bara - Camping - Caravaning - Bungalows - Spa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.playabara.es\/fr\/travaille-avec-nous\/","og_locale":"fr_FR","og_type":"article","og_title":"TRAVAILLE AVEC NOUS","og_description":"TRAVAILLE AVEC NOUS Nous recherchons des personnes impliqu\u00e9es et ayant une vocation pour le service \u00e0 la client\u00e8le. NOUS VOUS RECHERCHONS FAITES PARTIE D&rsquo;UNE ENTREPRISE LEADER Playa Bara, fond\u00e9e en 1970, a plus de 50 ans d&#8217;histoire dans l&#8217;accueil des campeurs dans une atmosph\u00e8re familiale et accueillante, r\u00e9compens\u00e9e comme l&#8217;un des meilleurs campings de la ...","og_url":"https:\/\/www.playabara.es\/fr\/travaille-avec-nous\/","og_site_name":"Playa Bara - Camping - Caravaning - Bungalows - Spa","article_modified_time":"2024-05-17T13:52:04+00:00","og_image":[{"url":"https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/02\/trabaja_icon.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.playabara.es\/fr\/travaille-avec-nous\/","url":"https:\/\/www.playabara.es\/fr\/travaille-avec-nous\/","name":"TRAVAILLE AVEC NOUS - Playa Bara - Camping - Caravaning - Bungalows - Spa","isPartOf":{"@id":"https:\/\/www.playabara.es\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.playabara.es\/fr\/travaille-avec-nous\/#primaryimage"},"image":{"@id":"https:\/\/www.playabara.es\/fr\/travaille-avec-nous\/#primaryimage"},"thumbnailUrl":"https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/02\/trabaja_icon.png","datePublished":"2024-02-01T17:24:29+00:00","dateModified":"2024-05-17T13:52:04+00:00","breadcrumb":{"@id":"https:\/\/www.playabara.es\/fr\/travaille-avec-nous\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.playabara.es\/fr\/travaille-avec-nous\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.playabara.es\/fr\/travaille-avec-nous\/#primaryimage","url":"https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/02\/trabaja_icon.png","contentUrl":"https:\/\/www.playabara.es\/wp-content\/uploads\/2024\/02\/trabaja_icon.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.playabara.es\/fr\/travaille-avec-nous\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.playabara.es\/fr\/accueil\/"},{"@type":"ListItem","position":2,"name":"TRAVAILLE AVEC NOUS"}]},{"@type":"WebSite","@id":"https:\/\/www.playabara.es\/fr\/#website","url":"https:\/\/www.playabara.es\/fr\/","name":"Playa Bara - Camping - Caravaning - Bungalows - Spa","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.playabara.es\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.playabara.es\/fr\/wp-json\/wp\/v2\/pages\/7590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.playabara.es\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.playabara.es\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.playabara.es\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.playabara.es\/fr\/wp-json\/wp\/v2\/comments?post=7590"}],"version-history":[{"count":5,"href":"https:\/\/www.playabara.es\/fr\/wp-json\/wp\/v2\/pages\/7590\/revisions"}],"predecessor-version":[{"id":8944,"href":"https:\/\/www.playabara.es\/fr\/wp-json\/wp\/v2\/pages\/7590\/revisions\/8944"}],"wp:attachment":[{"href":"https:\/\/www.playabara.es\/fr\/wp-json\/wp\/v2\/media?parent=7590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}